{"id":194,"date":"2012-01-05T14:58:22","date_gmt":"2012-01-05T13:58:22","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/animaladas\/?p=194"},"modified":"2012-01-05T14:58:22","modified_gmt":"2012-01-05T13:58:22","slug":"puede-no-ser-bueno-elegir-lo-mejor","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/animaladas\/2012\/01\/05\/puede-no-ser-bueno-elegir-lo-mejor\/","title":{"rendered":"Puede no ser bueno elegir lo mejor"},"content":{"rendered":"<p><a href=\"\/animaladas\/wp-content\/uploads\/sites\/24\/2012\/01\/Taeniopygia-guttata.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-195\" title=\"Taeniopygia guttata\" src=\"\/animaladas\/wp-content\/uploads\/sites\/24\/2012\/01\/Taeniopygia-guttata.jpeg\" alt=\"\" width=\"318\" height=\"159\" srcset=\"https:\/\/blogs.elcorreo.com\/animaladas\/wp-content\/uploads\/sites\/24\/2012\/01\/Taeniopygia-guttata.jpeg 318w, https:\/\/blogs.elcorreo.com\/animaladas\/wp-content\/uploads\/sites\/24\/2012\/01\/Taeniopygia-guttata-300x150.jpeg 300w\" sizes=\"auto, (max-width: 318px) 100vw, 318px\" \/><\/a>Escoger pareja, -escogerla bien, se entiende-, tiene una gran importancia, ya que de ello depende, en gran medida, el poder transmitir los genes propios a la siguiente generaci\u00f3n. Cuando los dos miembros de la pareja cooperan para criar a la prole, es bueno que la pareja sea fuerte, que est\u00e9 muy capacitada para adquirir recursos, porque de esa forma contribuir\u00e1 a sacar adelante a la progenie con mayor facilidad. Y si no cooperan ambos o, sencillamente, no hay ninguna forma de cuidado parental, tambi\u00e9n es importante escoger como pareja a un individuo con \u201cbuenos genes\u201d, pues ser\u00e1n esos genes cuyas copias ser\u00e1n transmitidas a la progenie com\u00fan.<\/p>\n<p>En la mayor\u00eda de las especies son las hembras las que realizan la elecci\u00f3n. El macho suele ser elegido, aunque no necesariamente haya de ser sujeto pasivo. De hecho, \u00e9ste ha de esforzarse en ser atractivo, en mostrar que es de buena calidad, que tiene \u201cbuenos genes\u201d, y hay diferentes formas de hacer eso. Las aves, por ejemplo, utilizan el trino y en algunos casos recurren al cortejo. Ambos, trino y cortejo, son indicadores adecuados de la calidad de los genes en las aves, como tambi\u00e9n pueden serlo caracter\u00edsticas tales como aspecto y color del plumaje o ciertos rasgos anat\u00f3micos.<\/p>\n<p>Como son las hembras las que eligen, han sido los rasgos externos que ellas han preferido los que han condicionado qu\u00e9 indicadores sexuales exhiben los machos, porque generaci\u00f3n tras generaci\u00f3n la elecci\u00f3n sistem\u00e1tica por parte de las hembras de determinados rasgos masculinos es lo que ha provocado que sean esos rasgos los que se han ido acentuando con el tiempo. Si, por ejemplo, las hembras de una especie prefieren a los machos que tienen el pico m\u00e1s largo y, por esa raz\u00f3n, escogen sistem\u00e1ticamente a esos machos, los picos de los machos de esa especie ser\u00e1n de generaci\u00f3n en generaci\u00f3n, cada vez m\u00e1s largos. A ese proceso se le denomina \u201cselecci\u00f3n sexual\u201d, y ha resultado ejercer efectos tan o m\u00e1s intensos en la evoluci\u00f3n de algunas especies que la selecci\u00f3n natural.<\/p>\n<p>Una de las nociones clave en este entramado conceptual es la de que los rasgos externos que prefieren las hembras son indicadores fidedignos de la calidad gen\u00e9tica de los machos y, por lo tanto, que existe un v\u00ednculo entre la adecuaci\u00f3n (el \u201cfitness\u201d darwiniano) y esos indicadores. Y de acuerdo con las predicciones te\u00f3ricas que se derivan del desarrollo de esa noci\u00f3n, las hembras siempre querr\u00e1n escoger a los machos de m\u00e1s alta calidad, que se supone que son aquellos cuyos indicadores (morfolog\u00eda externa, caracter\u00edsticas del trino, o calidad del cortejo) as\u00ed lo expresan.<\/p>\n<p>Sin embargo, resulta que no siempre ocurre eso, ya que las hembras escogen machos de diferentes fenotipos (caracter\u00edsticas que se expresan). Adem\u00e1s, seg\u00fan algunos especialistas, es posible que sea la calidad de la hembra una de las caracter\u00edsticas que condiciona su preferencia por unos rasgos masculinos u otros. En el seno de una poblaci\u00f3n hay diferencias fenot\u00edpicas entre individuos; como consecuencia de esas diferencias no son iguales las tasas de crecimiento y producci\u00f3n de unos y de otros, as\u00ed como la cantidad de recursos que destinan al mantenimiento de las funciones corporales o a la reproducci\u00f3n. Y por lo tanto, los individuos de una misma poblaci\u00f3n pueden encontrarse en condiciones fisiol\u00f3gicas muy diferentes, condiciones que tienen su reflejo en los indicadores de calidad que hemos visto (morfolog\u00eda, y caracter\u00edsticas del trino o del cortejo).<\/p>\n<p>Como antes he se\u00f1alado, es muy posible que el fenotipo de la hembra sea uno de los criterios m\u00e1s importantes a la hora de elegir al macho. Es posible, -por concretar esta idea un poco m\u00e1s-, que las hembras escojan a machos cuyos indicadores den cuenta de una calidad fenot\u00edpica similar a la propia. Y esa es una posibilidad que ha tratado de verificar un equipo de investigaci\u00f3n mediante un experimento.<\/p>\n<p>Criaron ejemplares de la especie <em>Taeniopygia guttata<\/em> (diamante mandar\u00edn) de diferentes caracter\u00edsticas, lo que consiguieron generando artificialmente nidadas de diferente tama\u00f1o: unas eran de 2 o 3 huevos y las otras de 5 o 6. Los pollos nacidos de los huevos pertenecientes a la nidada peque\u00f1a eran de mayor calidad que los pertenecientes a la nidada grande, ya que los primeros se encuentran mejor alimentados que los segundos. Adem\u00e1s, las diferencias que se producen as\u00ed, perduran a lo largo del tiempo y se mantienen hasta la madurez.<\/p>\n<p><a href=\"\/animaladas\/wp-content\/uploads\/sites\/24\/2012\/01\/diamantes-mandarines.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-196\" title=\"diamantes mandarines\" src=\"\/animaladas\/wp-content\/uploads\/sites\/24\/2012\/01\/diamantes-mandarines.jpeg\" alt=\"\" width=\"240\" height=\"198\" \/><\/a>El experimento confirm\u00f3 la hip\u00f3tesis de partida. Ante diferentes posibilidades de elecci\u00f3n, solo las hembras de alta calidad escogieron machos de alta calidad. Las de baja calidad los seleccionaron de baja calidad a ellos tambi\u00e9n. As\u00ed pues, el haber sido criados bajo diferentes condiciones tiene consecuencias duraderas en los diamantes mandarines y los criterios de selecci\u00f3n del macho por parte de la hembra son unas de esas consecuencias. Por otra parte, sean de alta o baja calidad, las primeras parejas en hacer la puesta fueron las que hab\u00edan formado p\u00e1jaros de la misma calidad; y eso ocurri\u00f3 porque fueron esas parejas las primeras en formarse y cuyas hembras fueron fecundadas antes. Este es un aspecto cr\u00edtico en la biolog\u00eda de esta especie. Los diamantes mandarines disponen de muy poco tiempo para incubar los huevos y para criar a los pollos, porque el entorno en el que viven es muy seco y muy corta la \u00e9poca de lluvias. Por eso, el periodo durante el que abunda el alimento es muy breve, y ese es el factor que limita la crianza de la nidada. Y es por esa raz\u00f3n por la que es muy importante que los periodos de incubaci\u00f3n y de crianza en el nido sean lo m\u00e1s cortos posibles y finalicen cuanto antes.<\/p>\n<p>Supongamos que una hembra de baja calidad no escoge un macho de calidad similar a la de ella y permanece a la espera de uno mejor. De proceder as\u00ed correr\u00eda el riesgo de no emparejarse o de hacerlo demasiado tarde, por lo que, en el peor de los casos, no se reproducir\u00eda. Por esa raz\u00f3n toma la decisi\u00f3n que m\u00e1s garant\u00edas ofrece y escoge al macho de calidad baja.<\/p>\n<p>Las condiciones ambientales del medio en que viven los diamantes mandarines son muy duras en el largo periodo de tiempo que trancurre entre dos estaciones reproductoras. De hecho, la tasa de supervivencia anual de los ejemplares adultos es muy baja, puesto que var\u00eda entre un 4% y un 28%. Por esa raz\u00f3n resulta fundamental acertar con la reproducci\u00f3n, pues es muy alto el riesgo de que desaparezca el patrimonio gen\u00e9tico del individuo que no acierta.<\/p>\n<p>A la vista de la t\u00e1ctica de emparejamiento de las hembras de <em>Taeniopygia guttata<\/em>, m\u00e1s de un lector o lectora estar\u00e1 pensando si ese comportamiento es exclusivo de esa especie y especies similares o si, por el contrario, tiene car\u00e1cter m\u00e1s general y ser\u00eda tambi\u00e9n propio, por ejemplo, de la especie humana. Pues bien, seg\u00fan estudios citados por los autores de esta investigaci\u00f3n, existe una cierta semejanza entre el comportamiento de <em>T. guttata<\/em> y el de los seres humanos. Las mujeres poco atractivas, o que tienen de s\u00ed mismas una imagen poco atractiva, suelen preferir emparejarse con hombres poco atractivos. Sin embargo, en el caso de los seres humanos no cabr\u00eda atribuir este comportamiento a las condiciones ambientales, sino a alg\u00fan otro factor, salvo que se trate de un comportamiento mucho m\u00e1s extendido. Por esa raz\u00f3n, en lo sucesivo es posible que se realicen investigaciones con m\u00e1s especies para comprobar si nos encontramos ante un rasgo muy extendido en el reino animal o si, por el contrario, se limita a las hembras de unas pocas especies entre las que se encuentra la nuestra.<\/p>\n<p>Fuente: Marie-Jeanne Holveck &#038; Katharina Riebel (2010): \u201cLow-quality females prefer low-quality males when choosing a mate\u201d <em>Proc. R. Soc. B <\/em>277: 153-160 (doi: 10.1098\/rspb.2009.1222)<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Escoger pareja, -escogerla bien, se entiende-, tiene una gran importancia, ya que de ello depende, en gran medida, el poder transmitir los genes propios a la siguiente generaci\u00f3n. Cuando los dos miembros de la pareja cooperan para criar a la prole, es bueno que la pareja sea fuerte, que est\u00e9 muy capacitada para adquirir recursos, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[191,217,224,248,470,601],"class_list":["post-194","post","type-post","status-publish","format-standard","hentry","category-reproduccion","tag-diamante-mandarin","tag-eleccion-de-pareja","tag-emparejamiento","tag-estrategia-reproductiva","tag-pareja","tag-taeniopygia-guttata"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/comments?post=194"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/194\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/media?parent=194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/categories?post=194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/tags?post=194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}