{"id":145,"date":"2011-03-06T22:31:00","date_gmt":"2011-03-06T22:31:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/animaladas\/?p=145"},"modified":"2011-03-06T22:31:00","modified_gmt":"2011-03-06T22:31:00","slug":"la-musarana-tolera-alcohol","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/animaladas\/2011\/03\/06\/la-musarana-tolera-alcohol\/","title":{"rendered":"La musara\u00f1a que tolera el alcohol"},"content":{"rendered":"\n<p class=\"MsoNormal\">Una de nuestras costumbres m\u00e1s arraigadas es la de consumir bebidas alcoh\u00f3licas. En el pasado de Europa, sobre todo en la Edad Media, era uno de los componentes principales de la dieta. Aunque hay seres humanos que no toleran el alcohol; no est\u00e1n capacitados para metabolizarlo y pueden sufrir graves intoxicaciones. Los seres humanos no somos los \u00fanicos animales que consumen alcohol. Otros primates y otros mam\u00edferos herb\u00edvoros consumen frutas fermentadas cuando tienen la ocasi\u00f3n.<\/p>\n<p class=\"MsoNormal\">El alcohol es propio de frutas maduras, llenas de nutrientes, y su efecto estimulante sobre el apetito resulta beneficioso para los herb\u00edvoros que, en ciertas ocasiones, tienen acceso a fuentes de alimento de car\u00e1cter muy ef\u00edmero. Por eso, cabe pensar que entre las plantas que producen frutas con cierto contenido en alcohol y sus consumidores, se ha producido un fen\u00f3meno de coevoluci\u00f3n con el correspondiente conjunto de adaptaciones rec\u00edprocas. De esa forma, las plantas ir\u00edan incluyendo cada vez m\u00e1s alcohol en el nectar de sus flores o en sus frutos, y los herb\u00edvoros ir\u00edan desarrollando una cada vez mayor tolerancia al alcohol y capacidad para metabolizarlo. La ventaja que se deriva para las plantas de esa relaci\u00f3n es que ven as\u00ed facilitada la polinizaci\u00f3n y la dispersi\u00f3n de las semillas.<\/p>\n<p>  <span style=\"font-size:11.0pt;font-family:Verdana;mso-ansi-language:ES-TRAD;<br \/>mso-fareast-language:ES-TRAD&#8221;>Hace tres a\u00f1os se public\u00f3 un estudio bastante curioso en el que se analizaban, precisamente, los t\u00e9rminos de una relaci\u00f3n de esa naturaleza entre una palmera (Eugeissona tristis) y una musara\u00f1a arbor\u00edcola (Ptilocercus lowii) de las selvas malayas. La flor de la palmera produce un nectar con un contenido en alcohol del 3\u20198%, producido por las abundantes levaduras presentes en ella. El estudio puso de manifiesto que si se imped\u00eda el acceso a las flores de las musara\u00f1as (y tambi\u00e9n, aunque en menor medida, de loris lentos, Nictycebus coucang), la palmera produc\u00eda la mitad de los frutos que los que produce bajo condiciones normales. Y tambi\u00e9n se observ\u00f3 que estos peque\u00f1os mam\u00edferos pasaban una media de dos horas por noche (son de h\u00e1bitos nocturnos) aliment\u00e1ndose del n\u00e9ctar y que ese n\u00e9ctar era, con diferencia, su principal fuente de alimento. No hay datos que permitan afirmar que lo que valoran las musara\u00f1as es el alcohol, ya que es posible que otros compuestos presentes en el n\u00e9ctar, o incluso las mismas levaduras, sean su verdadero objeto de deseo, pero no cabe duda de que han desarrollado una enorme capacidad para tolerar el alcohol. Hasta qu\u00e9 punto son tolerantes que, si se corrigen los efectos del tama\u00f1o, el alcohol ingerido por las musara\u00f1as ser\u00eda m\u00e1s que suficiente para provocar una buena borrachera a cualquiera de nosotros.<\/span><br \/>\n<font class=\"Apple-style-span\" size=\"4\"><span class=\"Apple-style-span\" style=\"font-size: 15px;\"><font class=\"Apple-style-span\" size=\"3\"><span class=\"Apple-style-span\" style=\"font-size: 13px;\"><br \/>\n<\/span><\/span><\/span><\/span><\/p>\n<div><span style=\"font-size:11.0pt;font-family:Verdana;mso-ansi-language:ES-TRAD;<br \/>mso-fareast-language:ES-TRAD&#8221;>Me encontr\u00e9 esta historia <A href=\"http:\/\/blogs.nature.com\/amch\/2010\/05\/02\/anthropological-studies-suggest-that-low-level?utm_source=feedburner&#038;utm_medium=twitter&#038;utm_campaign=Feed%3A+ResearchBloggingAllEnglish+%28Research+Blogging+-+English+-+All+Topics%29\" title=\"http:\/\/blogs.nature.com\/amch\/2010\/05\/02\/anthropological-studies-suggest-that-low-level?utm_source=feedburner&#038;utm_medium=twitter&#038;utm_campaign=Feed%3A+ResearchBloggingAllEnglish+%28Research+Blogging+-+English+-+All+Topics%29\" id=\"link_0\">aqu\u00ed<\/a>.<\/span><\/div>\n<div><span style=\"font-size:11.0pt;font-family:Verdana;mso-ansi-language:ES-TRAD;<br \/>mso-fareast-language:ES-TRAD&#8221;><br \/>\nEl art\u00edculo citado, es este: Wiens, F., Zitzmann, A., Lachance, M., Yegles, M., Pragst, F., Wurst, F., von Holst, D., Guan, S., &#038; Spanagel, R. (2008). Chronic intake of fermented floral nectar by wild treeshrews <em>Proceedings of the National Academy of Sciences, 105<\/em> (30), 10426-10431 DOI: <A href=\"http:\/\/dx.doi.org\/10.1073\/pnas.0801628105\">10.1073\/pnas.0801628105<\/a><\/span><\/div>\n<div><span style=\"font-size:11.0pt;font-family:Verdana;mso-ansi-language:ES-TRAD;<br \/>mso-fareast-language:ES-TRAD&#8221;><br \/>\n<\/span><\/div>\n<div><span style=\"font-size:11.0pt;font-family:Verdana;mso-ansi-language:ES-TRAD;<br \/>mso-fareast-language:ES-TRAD&#8221;><A href=\"http:\/\/dx.doi.org\/10.1073\/pnas.0801628105\"><\/a><o:p><\/o:p>La musara\u00f1a arbor\u00edcola no es el \u00fanico animal que consume alcohol<\/span><\/div>\n<div><span style=\"font-size:11.0pt;font-family:Verdana;mso-ansi-language:ES-TRAD;<br \/>mso-fareast-language:ES-TRAD&#8221;><\/p>\n<p>     <\/span><\/div>\n<p><object width=\"480\" height=\"390\" style=\"border-style: initial; border-color: initial; border-top-width: 0px; border-right-width: 0px; border-bottom-width: 0px; border-left-width: 0px; border-style: initial; border-color: initial; background-image: none; background-attachment: initial; background-origin: initial; background-clip: initial; background-color: initial; margin-top: 0px; margin-right: 0px; margin-bottom: 0px; margin-left: 0px; background-position: initial initial; background-repeat: initial initial; \"><param  name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/AmQPwgV-WbQ?fs=1&#038;hl=es_ES\"><\/param><param  name=\"allowFullScreen\" value=\"true\"><\/param><param  name=\"allowscriptaccess\" value=\"always\"><\/param><embed  src=\"\/\/www.youtube.com\/v\/AmQPwgV-WbQ?fs=1&#038;hl=es_ES\" type=\"application\/x-shockwave-flash\" allowscriptaccess=\"always\" allowfullscreen=\"true\" width=\"480\" height=\"390\"><\/embed><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Una de nuestras costumbres m\u00e1s arraigadas es la de consumir bebidas alcoh\u00f3licas. En el pasado de Europa, sobre todo en la Edad Media, era uno de los componentes principales de la dieta. Aunque hay seres humanos que no toleran el alcohol; no est\u00e1n capacitados para metabolizarlo y pueden sufrir graves intoxicaciones. Los seres humanos no [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[30,250,425,521],"class_list":["post-145","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-alcohol","tag-eugeissona-tristis","tag-musarana-arboricola","tag-ptilocercus-lowii"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/comments?post=145"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/145\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/media?parent=145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/categories?post=145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/tags?post=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}