{"id":131,"date":"2010-11-05T07:08:00","date_gmt":"2010-11-05T07:08:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/animaladas\/?p=131"},"modified":"2010-11-05T07:08:00","modified_gmt":"2010-11-05T07:08:00","slug":"colosos-la-sabana-y-los-oceanos","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/animaladas\/2010\/11\/05\/colosos-la-sabana-y-los-oceanos\/","title":{"rendered":"Colosos de la sabana y de los oc\u00e9anos"},"content":{"rendered":"\n<p class=\"MsoNormal\">En \u201cGigantes abisales\u201d vimos el calamar gigante y otros animales de gran tama\u00f1o que habitan en profundidades oce\u00e1nicas abisales. Aqu\u00ed tambi\u00e9n voy a referirme a animales de gran tama\u00f1o, pero en este caso se trata de dos especies, una terrestre y marina la otra. La terrestre es el elefante africano, y la marina es el cachalote. Aunque no est\u00e9 pr\u00f3xima una especie de la otra, tienen algunas caracter\u00edsticas en com\u00fan, algo que resulta hasta cierto punto sorprendente, dado que ocupan medios muy diferentes.<\/p>\n<p class=\"MsoNormal\">Ambas viven en medios muy estables, porque tanto el mar como la sabana experimentan pocos cambios a lo largo del tiempo. Son de vida prolongada: pueden llegar a los sesenta a\u00f1os de edad, y ambas alcanzan la madurez sexual en su segunda d\u00e9cada de vida. El periodo de tiempo que transcurre entre alumbramientos es de unos cinco a\u00f1os en ambos casos, y a partir de los cuarenta a\u00f1os de edad disminuye el esfuerzo reproductor. Las elefantas m\u00e1s viejas cumplen una importante funci\u00f3n en el grupo de elefantes y muy probablemente, lo mismo ocurre con las hembra de cachalote de m\u00e1s edad. Las hembras m\u00e1s viejas de ambas especies son verdaderas matriarcas en los grupos de hembras y de cr\u00edas que dirigen.<\/p>\n<p class=\"MsoNormal\">Consumen enormes cantidades de alimento a lo largo de sus vidas y para adquirirlo hacen desplazamientos a lo largo de grandes distancias. Los elefantes se alimentan de diferentes especies vegetales y, como he se\u00f1alado, necesitan comer grandes cantidades. Si no tenemos en cuenta a la especie humana, los elefantes africanos son los animales que mayor efecto han causado en \u00c1frica. No es f\u00e1cil saber cu\u00e1l es el efecto que causan los cachalotes sobre el entorno en el que viven. Consumen todo tipo de presas, incluidos calamares (de varias especies) y peces (tambi\u00e9n de muchas especies) y tambi\u00e9n realizan grandes desplazamientos para alimentarse y reproducirse. Si bien el n\u00famero total de cachalotes se ha reducido sensiblemente a lo largo de los siglos XIX y XX por efecto de la caza indiscriminada, en la actualidad consumen del orden de cien millones de toneladas de alimentos, una cantidad equivalente a la que extraen los seres humanos del mar mediante la pesca.<\/p>\n<p class=\"MsoNormal\">Un grupo de elefantes est\u00e1 formado por unos diez individuos. Las familias son matrilineales y las hembras pasan, muy probablemente, toda su vida en el mismo grupo familiar. Los miembros del grupo hacen muchas cosas al mismo tiempo y en compa\u00f1\u00eda: se mueven, comen, beben y descansan juntos. Los miembros de una misma familia se tocan, se huelen y se acarician unos a otros. Para comunicarse entre ellos utilizan el tacto, el olor, la vista y, sobre todo, el oido. Gracias a ello mantienen unos v\u00ednculos tan estrechos. Emiten y reciben infrasonidos de entre 12 y 36 herzios, algunos de ellos de m\u00e1s de 100 dB de potencia. De hecho, elefantes separados hasta por cuatro km de distancia pueden comunicarse mediante esos infrasonidos.<\/p>\n<p class=\"MsoNormal\">La estructura de grupo de los cachalotes es similar a la anterior, aunque es menos lo que se sabe de ellos; el grupo lo forman del orden de una docena de cachalotes. La mayor parte del tiempo la pasan bajo el agua, cazando. Las inmersiones suelen ser de unos 400 m de profundidad, aunque pueden ser m\u00e1s prolongadas, y vienen a durar unos 40 min en promedio. Mientras se encuentran bajo el agua producen unos sonidos o chasquidos caracter\u00edsticos, -a los que se denomina klik-, que emiten a intervalos regulares. Las frecuencias de esos sonidos son variadas dentro de un intervalo muy amplio: van de 200 a 32.000 herzios. Parece ser que se trata de se\u00f1ales de ecolocalizaci\u00f3n que utilizan para localizar a sus presas.<\/p>\n<p class=\"MsoNormal\"><span style=\"\">En los grupos con cr\u00edas, el grupo asume la tarea de cuidar de los m\u00e1s peque\u00f1os y no es raro que una cr\u00eda mame de una hembra adulta que no es su madre; ese comportamiento tambi\u00e9n es habitual entre los elefantes. Al atardecer dejan de sumergirse y permanecen nadando en grupo durante seis horas, lentamente, con tranquilidad, jugando y acariciandose unos a otros con las aletas y con las mejillas. Cuando juegan de ese modo, producen secuencias de chasquidos (kliks) y es muy posible que esos chasquidos sean elementos de un sistema de comunicaci\u00f3n que ayude a cohesionar el grupo y a coordinar sus movimientos.<\/span><\/p>\n<p>  <span style=\"font-size: 12pt; font-family: \"Calibri\",\"sans-serif\";\">Elefantes y cachalotes son mam\u00edferos grandes y de inteligencia considerable. Sus grupos tienen estructuras semejantes. Ambos se sirven del conocimiento que atesoran los miembros m\u00e1s viejos del grupo, sobre todo en lo relativo a la localizaci\u00f3n del alimento. La informaci\u00f3n con que cuentan los miembros de m\u00e1s edad les sirve para saber c\u00f3mo var\u00edan los recursos alimenticios a lo largo de las estaciones, o cu\u00e1ndo y d\u00f3nde se puede encontrar agua; en ambos casos se trata de informaci\u00f3n esencial para la supervivencia de los integrantes del grupo. Seguramente, el hecho de que la vida de cachalotes y elefantes sea tan prolongada tiene mucho que ver con ese conocimiento ecol\u00f3gico que poseen los miembros de m\u00e1s edad del grupo.<\/span><\/p>\n<p class=\"MsoNormal\"><A href=\"http:\/\/www.youtube.com\/watch?v=qaidpx3b0Jg\" title=\"http:\/\/www.youtube.com\/watch?v=qaidpx3b0Jg\" id=\"link_0\">Aqu\u00ed<\/a> <span style=\"font-size: 12pt; font-family: \"Calibri\",\"sans-serif\";\">se puede<\/span>n ver im\u00e1genes impresionantes en las que se muestra c\u00f3mo protege una madre cachalote a su cr\u00eda de los ataques de un grupo de orcas, y m\u00e1s adelante, c\u00f3mo se organiza el grupo de cachalotes para defenderla entre todas (no es posible insertar el video, por eso se adjunta el link).<\/p>\n<p class=\"MsoNormal\">Y en el siguiente video, se muestran im\u00e1genes de cachalotes sumergi\u00e9ndose:<\/p>\n<p><object style=\"border: 0pt none; background: none repeat scroll 0% 0% transparent; margin: 0pt;\" width=\"480\" height=\"385\"><param  name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/4I_6IpoRI-M?fs=1&#038;hl=es_ES\"><\/param><param  name=\"allowFullScreen\" value=\"true\"><\/param><param  name=\"allowscriptaccess\" value=\"always\"><\/param><embed  src=\"\/\/www.youtube.com\/v\/4I_6IpoRI-M?fs=1&#038;hl=es_ES\" type=\"application\/x-shockwave-flash\" allowscriptaccess=\"always\" allowfullscreen=\"true\" width=\"480\" height=\"385\"><\/embed><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En \u201cGigantes abisales\u201d vimos el calamar gigante y otros animales de gran tama\u00f1o que habitan en profundidades oce\u00e1nicas abisales. Aqu\u00ed tambi\u00e9n voy a referirme a animales de gran tama\u00f1o, pero en este caso se trata de dos especies, una terrestre y marina la otra. La terrestre es el elefante africano, y la marina es el [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[103,209,220,254,444],"class_list":["post-131","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-cachalotes","tag-ecolocalizacion","tag-elefantes","tag-familia-matrilineal","tag-oido"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/comments?post=131"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/131\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/media?parent=131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/categories?post=131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/tags?post=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}