{"id":130,"date":"2010-10-29T07:21:00","date_gmt":"2010-10-29T07:21:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/animaladas\/?p=130"},"modified":"2010-10-29T07:21:00","modified_gmt":"2010-10-29T07:21:00","slug":"el-mejillon-cebra-bivalvo-plaga","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/animaladas\/2010\/10\/29\/el-mejillon-cebra-bivalvo-plaga\/","title":{"rendered":"El mejill\u00f3n cebra, bivalvo plaga"},"content":{"rendered":"\n<p class=\"MsoNormal\">Cuando pensamos en plagas animales, los que nos vienen a la cabeza suelen ser insectos, como cucarachas o langostas, por ejemplo. Pero esas no son las \u00fanicas especies que pueden formar plagas. Entre ellos, hay tambi\u00e9n un bivalvo, y muy da\u00f1ino adem\u00e1s.<\/p>\n<p class=\"MsoNormal\">En agosto de 2007 se detect\u00f3 la presencia de larvas de un bivalvo de agua dulce en el embalse guipuzcoano de Lareo; me refiero al mejill\u00f3n cebra. El descubrimiento encedi\u00f3 la alarma, puesto que esa fue la primera ocasi\u00f3n en que se han encontrado larvas de esta especie en alg\u00fan cauce o masa de agua de la vertiente cant\u00e1brica. Afortunadamente, parece que no hay motivo de alarma, no por ahora al menos; seg\u00fan las investigaciones que se realizaron despu\u00e9s de ese descubrimiento inicial, no se han vuelto a detectar esas larvas en el pantano. <\/p>\n<p class=\"MsoNormal\">El nombre cient\u00edfico de este bivalvo es Dreissena polymorpha, y aunque su nombre com\u00fan es mejill\u00f3n cebra, no es un mejill\u00f3n. No tiene nada que ver con los mejillones tan bien conocidos entre nosotros. De hecho, Dreissena se encuentra m\u00e1s pr\u00f3ximo a las almejas y bivalvos similares que a los mejillones. El nombre com\u00fan obedece al hecho de que tienen cierta semejanza con los mejillones en la forma, aunque el mejill\u00f3n cebra es m\u00e1s peque\u00f1o que los mejillones marinos. Tambi\u00e9n se parecen a los mejillones en que se adhieren al sustrato del mismo modo a como lo hacen los mejillones, con un \u201cbiso\u201d, hebras de naturaleza prot\u00e9ica que se adhieren a superficies s\u00f3lidas y que tienen una gran resistencia. Y el apelativo \u201ccebra\u201d se refiere al dibujo a rayas de la concha, que recuerda a las l\u00edneas de las cebras.<\/p>\n<p class=\"MsoNormal\">Dreissena polymorpha es un bivalvo de agua dulce de peque\u00f1o tama\u00f1o; puede alcanzar los 5 cm de longitud. Procede de los lagos del sudeste de Rusia, pero es una especie invasora, y se ha distribuido por much\u00edsimos lugares del planeta. Tolera durante periodos prolongados aguas de diferentes salinidades y en lo relativo a la temperatura, tiene un rango de tolerancia bastante amplio. Adem\u00e1s, desde el punto de vista biol\u00f3gico es muy eficiente, puesto que produce cantidades de huevos alt\u00edsimas, m\u00e1s altas que las que suelen producir otros bivalvos de agua dulce.<\/p>\n<p class=\"MsoNormal\"><span style=\"\">Durante el siglo XIX se extendi\u00f3 por los canales del continente europeo hasta llegar al Mar del Norte y a Gran Breta\u00f1a. Al sur de Europa lleg\u00f3 m\u00e1s tarde; durante el \u00faltimo cuarto del pasado sigl\u00f3 alcanz\u00f3 las pen\u00ednsulas ib\u00e9rica e it\u00e1lica. En 1988 lleg\u00f3 a Norteam\u00e9rica, a los Grandes Lagos y desde entonces no ha dejado de expandirse, poco a poco, por toda Norteam\u00e9rica. Esa gran extensi\u00f3n se ha producido gracias a los traslados de peque\u00f1as embarcaciones de pesca o de recreo entre distintos r\u00edos o lagos; las larvas y peque\u00f1os bivalvos van adheridos al fondo de las embarcaciones, lo que dificulta su detecci\u00f3n.<\/span> Al parecer eso es lo que ocurri\u00f3 en el pantano de Lareo. No obstante, aunque se encuentra en el Ebro, todav\u00eda no ha alcanzado los r\u00edos de la vertiente cant\u00e1brica.<\/p>\n<p class=\"MsoNormal\">Dreissena produce da\u00f1os tremendos. En muchas ocasiones ha desplazado a las especies aut\u00f3ctonas. Son capaces de asentarse encima de las poblaciones de bivalvos preexistentes, matando a los que quedan debajo. Surgen de esa forma nuevos asentamientos de mejillones cebra. Adem\u00e1s, causn grandes da\u00f1os cuando se adhieren a estructuras de madera o de otros materiales empleados en obras propias de lagos, pantanos o r\u00edos, como tuber\u00edas, canales, vigas de soporte y bombas de trasiego. Si penetran en el interior de una tuber\u00eda, en pocos a\u00f1os pueden llegar a cegar su luz. Ello hace que se deban gastar importantes cantidades de dinero en limpiar y restaurar esas estructuras.<\/p>\n<p class=\"MsoNormal\">Se conoce un pez que come mejillones cebra, es el pez de agua dulce Rutilus rutilus. En algunas localidades, Dreissena representa hasta el 90% del total ingerido por esos peces. Sin embargo, todav\u00eda no se conoce ning\u00fan lugar en el que Rutilus haya llegado a limitar las poblaciones de mejill\u00f3n cebra.<\/p>\n<p>  <span style=\"font-size: 11pt; line-height: 115%; font-family: \"Calibri\",\"sans-serif\";\">No es ninguna exageraci\u00f3n afirmar que Dreissena polymorpha una peligrosa plaga. Adem\u00e1s de ser un enemigo de la biodiversidad de r\u00edos y lagos, los da\u00f1os econ\u00f3micos que puede causar son tremendos.<\/p>\n<p><\/span><br \/>\n<object style=\"border: 0pt none; background: none repeat scroll 0% 0% transparent; margin: 0pt;\" width=\"480\" height=\"385\"><param  name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/Qgn6f4LusrM?fs=1&#038;hl=es_ES\"><\/param><param  name=\"allowFullScreen\" value=\"true\"><\/param><param  name=\"allowscriptaccess\" value=\"always\"><\/param><embed  src=\"\/\/www.youtube.com\/v\/Qgn6f4LusrM?fs=1&#038;hl=es_ES\" type=\"application\/x-shockwave-flash\" allowscriptaccess=\"always\" allowfullscreen=\"true\" width=\"480\" height=\"385\"><\/embed><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Cuando pensamos en plagas animales, los que nos vienen a la cabeza suelen ser insectos, como cucarachas o langostas, por ejemplo. Pero esas no son las \u00fanicas especies que pueden formar plagas. Entre ellos, hay tambi\u00e9n un bivalvo, y muy da\u00f1ino adem\u00e1s. En agosto de 2007 se detect\u00f3 la presencia de larvas de un bivalvo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[93,206,402,500],"class_list":["post-130","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-bivalvos","tag-dreissena-polymorpha","tag-mejillon-cebra","tag-plaga"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/comments?post=130"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/130\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/media?parent=130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/categories?post=130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/tags?post=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}