{"id":125,"date":"2010-09-26T22:43:00","date_gmt":"2010-09-26T22:43:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/animaladas\/?p=125"},"modified":"2010-09-26T22:43:00","modified_gmt":"2010-09-26T22:43:00","slug":"el-pez-la-cabeza-transparente","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/animaladas\/2010\/09\/26\/el-pez-la-cabeza-transparente\/","title":{"rendered":"El pez de la cabeza transparente"},"content":{"rendered":"\n<p class=\"MsoNormal\">En la entrada anterior me ocup\u00e9 de los ojos tubulares y para terminar insert\u00e9 un video en el que aparece uno de los peces que tiene ojos tubulares, Macropinna microstoma. Al final del texto volver\u00e9 a insertar el video, porque es de esta misma especie de la que trato en esta entrada. Esta especie es la \u00fanica conocida del g\u00e9nero Macropinna, que pertenece a la familia Opisthoproktidae. Los peces de esta especie viven en las zonas sub\u00e1rticas y templadas del Oc\u00e9ano Pac\u00edfico, a profundidades que van de los 600 a los 1.000 m, o lo que es lo mismo, en las \u00e1reas de mayor profundidad dentro de la zona mesopel\u00e1gica. Su rango de distribuci\u00f3n geogr\u00e1fica se extiende desde el Mar de Bering en el norte hasta el Jap\u00f3n por el oeste y Baja California por el este.<\/p>\n<p class=\"MsoNormal\">La especie fue descubierta en 1939, por lo que sus caracter\u00edsticas son conocidas desde hace tiempo. Son peces peque\u00f1os, de 4-5 cm de longitud y lo m\u00e1s rese\u00f1able de su aspecto es el peque\u00f1o tama\u00f1o de su boca y los dos ojos tubulares que se encuentran en la parte superior de la cabeza y que apuntan hacia arriba. El nombre com\u00fan en ingl\u00e9s de esta especie de opistopr\u00f3ctidos es \u201cbarreleye\u201d, y en espa\u00f1ol se les llama \u201cojobarril\u201d. <\/p>\n<p class=\"MsoNormal\">Hasta hace poco tiempo era un misterio el modo en que se las arregla Macropinna para atrapar a sus presas, puesto que sus ojos tubulares est\u00e1n en la zona dorsal del cuerpo y la boca se encuentra en la parte anterior. Esto es, la boca no se halla dentro del campo de visi\u00f3n. As\u00ed pues, \u00bfc\u00f3mo se las arregla para atrapar sus presas si los ojos miran hacia arriba y la boca est\u00e1 dirigida al frente? <\/p>\n<p class=\"MsoNormal\">Hasta que en 2008 no se publicaron las observaciones hechas en 2004 \u201cin situ\u201d por un grupo de investigadores del Acuario de la Bah\u00eda de Monterrey (California), no se ha aclarado el modo de alimentaci\u00f3n, parad\u00f3jico, de estos peces. Gracias a las im\u00e1genes grabadas en video hemos tenido conocimiento de su verdadero aspecto. Cuando enviaron el aparato para tomar im\u00e1genes y recoger ejemplares al lecho marino y consiguieron grabar las primeras im\u00e1genes de Macropinna, lo que m\u00e1s llamativo les result\u00f3 fue que la cabeza de estos peces era mayor de lo que pensaban y que adem\u00e1s\u2026. \u00a1era transparente! Desde 1939 hasta entonces nadie se hab\u00eda percatado de ese hecho, seguramente porque los ejemplares capturados con redes de aguas profundas llegaban muy da\u00f1ados a la superficie y no se conservaba una estructura tan fr\u00e1gil.<\/p>\n<p class=\"MsoNormal\">En el video se aprecia con nitidez el aspecto real de la cabeza y su transparencia. La cubierta transparente comienza en el punto en el que se encuentran las rosetas nasales, estructuras que asemejan unos ojos, y termina en el punto en que empiezan las escamas en la zona dorsal. Los ojos tubulares quedan protegidos dentro de esa cubierta transparente y se disponen bajo unas copas verdes que se ven con gran claridad en las im\u00e1genes; esas copas son las lentes de los ojos y el pigmento verde permite absorver la escas\u00edsima luz que llega a esas profundidades. De esa forma pueden detectar mejor la luz procedente de los organismos bioluminiscentes que pululan por all\u00ed abajo. Como he se\u00f1alado antes, las estructuras que se aprecian encima de la boca y que parecen ojos tristes son orificios nasales y los ojos verdaderos se encuentran en el interior, en la parte superior, inmersos en un fluido que llena la c\u00e1mara que configura el escudo craneal transparente. <\/p>\n<p class=\"MsoNormal\">Pero adem\u00e1s de lo anterior, los investigadores que operaban el veh\u00edculo submarino hicieron otro descubrimiento. Si bien los ojos se encuentran apuntando hacia arriba, resulta que pueden modificar su disposici\u00f3n y orientarlos hacia delante. Al examinar los ejemplares trasladados al laboratorio observaron que el m\u00e1ximo \u00e1ngulo de giro de los ojos lleg\u00f3 a ser de unos 75\u00ba. Era sabido que estos peces tienen una musculatura muy compleja, pero hasta que no se vio girar los ojos, no se pudo atribuir esa gran complejidad a nada concreto. Cuando los ojos se encuentran en su posici\u00f3n habitual, informan de lo que ocurre por encima de ellos y cuando detectan algo interesante para comer, pueden acercarse al plano de la boca para mejorar la efectividad del ataque a la presa potencial. Por otra parte, el poder mover los ojos de esa manera incrementa notablemente el campo visual, y adem\u00e1s de ver lo que ocurre por arriba, tambi\u00e9n pueden ver lo que pasa a los lados y al frente. As\u00ed pues, es la capacidad para girar los ojos lo que permite a Macropinna ver ante su boca la presa que se dispone a atrapar.<\/p>\n<p class=\"MsoNormal\">Los ojos de Macropinna son ejemplos de una adaptaci\u00f3n evolutiva espectacular. Si ya era notable la anatom\u00eda y funcionamiento de los ojos tubulares, as\u00ed como su valor adaptativo en aguas de luz tan escasa, la posibilidad de hacer girar los ojos con tanta amplitud multiplica de forma considerable sus prestaciones en ese entorno tan especial.<\/p>\n<p class=\"MsoNormal\">\n<p><object style=\"border: 0pt none; background: none repeat scroll 0% 0% transparent; margin: 0pt;\" width=\"640\" height=\"385\"><param  name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/loAOXX9bE_Q?fs=1&#038;hl=es_ES\"><\/param><param  name=\"allowFullScreen\" value=\"true\"><\/param><param  name=\"allowscriptaccess\" value=\"always\"><\/param><embed  src=\"\/\/www.youtube.com\/v\/loAOXX9bE_Q?fs=1&#038;hl=es_ES\" type=\"application\/x-shockwave-flash\" allowscriptaccess=\"always\" allowfullscreen=\"true\" width=\"640\" height=\"385\"><\/embed><\/object><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En la entrada anterior me ocup\u00e9 de los ojos tubulares y para terminar insert\u00e9 un video en el que aparece uno de los peces que tiene ojos tubulares, Macropinna microstoma. Al final del texto volver\u00e9 a insertar el video, porque es de esta misma especie de la que trato en esta entrada. Esta especie es [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[26,389,446,646],"class_list":["post-125","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-aguas-profundas","tag-macropinna","tag-ojos-tubulares","tag-vision"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/comments?post=125"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/posts\/125\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/media?parent=125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/categories?post=125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/animaladas\/wp-json\/wp\/v2\/tags?post=125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}