{"id":99,"date":"2009-09-03T10:25:00","date_gmt":"2009-09-03T10:25:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/aletheia\/?p=99"},"modified":"2009-09-03T10:25:00","modified_gmt":"2009-09-03T10:25:00","slug":"el-paquete-basagoiti","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/aletheia\/2009\/09\/03\/el-paquete-basagoiti\/","title":{"rendered":"El &#8220;paquete&#8221; de Basagoiti"},"content":{"rendered":"<p><IMG src=\"\/aletheia\/wp-content\/uploads\/sites\/7\" id=\"img_1\" class=\"imgdcha\">Desde que Antonio Basagoiti sustituyera a Mar\u00eda San Gil al frente del PP vasco en 2008, algo ha cambiado en este partido. Frente a la m\u00e1s apocada figura de la primera, Basagoiti apuesta por no pasar nunca inadvertido. &#8220;Si los medios quieren carne -parece pensar-, yo les dar\u00e1 carnaza&#8221;. La \u00faltimas de estas actuaciones se refiere a la decisi\u00f3n del juez Eloy Jim\u00e9nez de dejar en libertad bajo fianza a la etarra Aranalde, a la que le ha faltado tiempo para huir tras salir de la c\u00e1rcel. Obviando el manido discurso de los pol\u00edticos del &#8220;respetamos las decisiones judiciales&#8221;, el l\u00edder de los populares vascos se expresa a su manera: &#8220;<strong>A alguien le tiene que caer un buen paquete<\/strong>&#8220;.<\/p>\n<p>Sin embargo, en su reciente trayectoria pol\u00edtica, se pueden encontrar muchas otras &#8220;joyas&#8221; de este tipo. El 5 de marzo, cuatro d\u00edas despu\u00e9s de las elecciones vascas, acudi\u00f3 a una entrevista a EITB para afirmar con la rotundidad que le caracteriza que &#8220;aqu\u00ed (en referencia al ente p\u00fablico vasco) <strong>se daba bola a ETA<\/strong>&#8220;. Meses despu\u00e9s, el 8 de agosto, dijo que &#8220;aqu\u00ed en Euskadi <strong>no nos chupamos el dedo<\/strong>. Sabemos que ETA y Batasuna son lo mismo&#8221;, y el 21 de agosto, afirm\u00f3 ver &#8220;<strong>muy pez<\/strong>&#8221; a L\u00f3pez en materia econ\u00f3mica. Y el lenguaraz pol\u00edtico popular cerr\u00f3 agosto con una referencia al txupinazo de Berriozar: &#8220;Cuantos m\u00e1s txupinazos lance la gente de ANV (&#8230;), m\u00e1s j\u00f3venes se ver\u00e1n identificados con esa <strong>basura<\/strong>&#8220;.<\/p>\n<p>En el fondo, las declaraciones de Basagoiti est\u00e1n de acuerdo a la de su antecesora en el cargo o de otros pol\u00edticos populares como Mayor Oreja, pero sus formas son m\u00e1s &#8220;populares&#8221;. Su objetivo, creo, es acercar su partido a los votantes del Pa\u00eds Vasco, un partido cuya imagen siempre ha pecado de cierta rigidez y envaramiento. Su imagen de presentaci\u00f3n, sobre una moto, ya dio una primera pista de lo que ven\u00eda.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Desde que Antonio Basagoiti sustituyera a Mar\u00eda San Gil al frente del PP vasco en 2008, algo ha cambiado en este partido. Frente a la m\u00e1s apocada figura de la primera, Basagoiti apuesta por no pasar nunca inadvertido. &#8220;Si los medios quieren carne -parece pensar-, yo les dar\u00e1 carnaza&#8221;. La \u00faltimas de estas actuaciones se [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[48,69,70,176,266,410,499,752],"class_list":["post-99","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-aranalde","tag-basagoiti","tag-basura","tag-declaraciones","tag-expresiones","tag-juez","tag-moto","tag-velasco"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/comments?post=99"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/99\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/media?parent=99"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/categories?post=99"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/tags?post=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}