{"id":92,"date":"2009-08-13T09:19:00","date_gmt":"2009-08-13T09:19:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/aletheia\/?p=92"},"modified":"2009-08-13T09:19:00","modified_gmt":"2009-08-13T09:19:00","slug":"las-tragedias-y-series-television","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/aletheia\/2009\/08\/13\/las-tragedias-y-series-television\/","title":{"rendered":"Las tragedias y las series de televisi\u00f3n"},"content":{"rendered":"<p><IMG src=\"\/aletheia\/files\/seriestr.jpg\" id=\"img_0\" class=\"imgcen\">En el anterior post habl\u00e9 sobre las series de televisi\u00f3n y el rasgo en com\u00fan que todas ellas tienen: un sentido irreal de la justicia, conocido como &#8220;happy ending&#8221;, que hace que siempre terminen bien. Este terminar bien significa que los forenses siempre dan con el asesino, los polic\u00edas resuelven todos sus casos (incluso los sucedidos hace veinte a\u00f1os. \u00a1La perfecci\u00f3n de los investigadores es tal, que se aburren con los cr\u00edmenes del presente para dedicarse a los pasados! ), los m\u00e9dicos dan con un diagn\u00f3stico complicad\u00edsimo o los presos escapan con \u00e9xito&#8230; Nada de esto tiene que ver con la realidad, pero habr\u00e1 que pensar que a la audiencia no le gusta que le cuenten la cruda realidad. Ya la viven todos los d\u00edas. La televisi\u00f3n como v\u00eda de escape, que se suele decir.<\/p>\n<p>Visto esto, me llama todav\u00eda m\u00e1s la atenci\u00f3n la afici\u00f3n que ten\u00edan los antiguos griegos hacia el teatro. Ten\u00edan comedias, s\u00ed (Arist\u00f3fanes es s\u00f3lo uno de los varios autores de comedias que hubo), pero los festivales giraban en torno a las tragedias. Como ocurre en la actualidad con las series, el final ya era conocido: Edipo matar\u00eda a su padre y yacer\u00eda con su madre. El &#8220;unhappy ending&#8221; estaba garantizado. \u00a1Qu\u00e9 distinto a nuestra costumbre de que todo termine felizmente! \u00a1Evadirse sufriendo!<\/p>\n<p>Mirar a la realidad cara a cara es propio del superhombre, que dir\u00eda Nietzsche; es sonreir, como hac\u00eda el S\u00edsifo de Camus, ante su irremediable destino ligado a la maldita roca monta\u00f1a arriba; pero es demasiado dif\u00edcil de soportar. \u00bfAlguien imagina una serie en la que el asesino siempre quede impune o todos los enfermos fallezcan?<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En el anterior post habl\u00e9 sobre las series de televisi\u00f3n y el rasgo en com\u00fan que todas ellas tienen: un sentido irreal de la justicia, conocido como &#8220;happy ending&#8221;, que hace que siempre terminen bien. Este terminar bien significa que los forenses siempre dan con el asesino, los polic\u00edas resuelven todos sus casos (incluso los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[92,219,237,527,671,715,734,742],"class_list":["post-92","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-bones","tag-edipo","tag-ending","tag-nietzsche","tag-series","tag-television","tag-tragedias","tag-unhappy"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/92","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/92\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/media?parent=92"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/categories?post=92"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/tags?post=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}