{"id":84,"date":"2009-06-23T09:09:00","date_gmt":"2009-06-23T09:09:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/aletheia\/?p=84"},"modified":"2009-06-23T09:09:00","modified_gmt":"2009-06-23T09:09:00","slug":"alguien-se-acuerda-del-airbus","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/aletheia\/2009\/06\/23\/alguien-se-acuerda-del-airbus\/","title":{"rendered":"\u00bfAlguien se acuerda del Airbus?"},"content":{"rendered":"<p><IMG src=\"\/aletheia\/wp-content\/uploads\/sites\/7\" id=\"img_0\" class=\"imgcen\">Hace ya tres semanas que el Airbus de Air France se estrell\u00f3 en el oc\u00e9ano Atl\u00e1ntico. 228 personas perecieron en un accidente de cuyas causas poco se sabe y por el que los medios ya han comenzado a olvidarse. Esto no es nada nuevo, pero es interesante exponer el modelo que se sigue para informar de estas tragedias y el tipo de &#8220;humanidad&#8221; que trasluce. Las etapas que necesariamente se suceden son las siguientes:<\/p>\n<p>1) Alarma general: con el conocimiento de la tragedia, se desata una asombrosa fiebre informativa. Se trata de dar todas las noticias que surjan, tengan sentido o no. En el caso del Airbus, en esos primeros momentos se dijo que el aparato hab\u00eda desaparecido sin dar ninguna se\u00f1al de aviso; pero tiempo despu\u00e9s se ha afirmado que dio 24 se\u00f1ales de alarma. Ni que decir tiene que las portadas de los peri\u00f3dicos abrir\u00e1n con el accidente al d\u00eda siguiente y llenar\u00e1n sus p\u00e1ginas con todos esos intentos de explicaci\u00f3n nacidos de la fiebre informativa. Como ya se ha dicho, aqu\u00ed vale pr\u00e1cticamente todo: desde la congelaci\u00f3n de los medidores de velocidad del aparato hasta un atentado. Adem\u00e1s, se buscan antecendentes que demuestren fallos t\u00e9cnicos en el avi\u00f3n siniestrado.<\/p>\n<p>2) Dos d\u00edas despu\u00e9s, la noticia sigue en portada y se empiezan a contar \u201chistorias humanas\u201d. Con el objetivo -dicen- de acercar la tragedia al lector, se rebusca entre las historias de los pasajeros aqu\u00e9llas que resulten m\u00e1s llamativas para subrayar lo evidente: lo tr\u00e1gico de una tragedia. Generalmente son historias de personas del pa\u00eds del medio de comunicaci\u00f3n que se trate, pero no es \u00e9ste una condici\u00f3n sine qua non. &#8220;El lector pide estas historias&#8221;, aseguran los periodistas.<\/p>\n<p>3) Al tercer d\u00eda comienzan a aparecer m\u00e1s hip\u00f3tesis que normalmente nada tienen que ver con las ofrecidas al calor de la noticia. Se multiplica el recurso a los expertos en busca de explicaciones, se siguen contando &#8220;historias humanas&#8221; y se intenta dar con un chivo expiatorio.<\/p>\n<p>4) El accidente comienza a diluirse en el tr\u00e1fago de noticias. Ya no se abre con ello el peri\u00f3dico y si sigue en portada, ya tiene una importancia menor. La fiebre ha pasado y comienza el proceso de &#8220;desmemorizaci\u00f3n&#8221; hasta que al cabo de una semana o poco m\u00e1s se deja de mencionar el accidente.<\/p>\n<p>Visto este modelo aproximado, cabe plantearse la &#8220;humanidad&#8221; que refleja. El contar esas historias personales supuestamente sirve para que el lector empatice con el desastre, para que se percate de que los fallecidos no son una simple cifra. Pero \u00bfes m\u00e1s humano seleccionar -pongamos- cinco casos y olvidar los 228 restantes que obviar todo ese morbo informativo que hace perseguir a los familiares de las v\u00edctimas en el aeropuerto de Par\u00eds? Es m\u00e1s, \u00bfa qu\u00e9 viene esa insistencia en buscar las historias humanas en un primer momento si al cabo de unos d\u00edas se procede a olvidar todo lo relativo a la tragedia?<\/p>\n<p>Probablemente el olvido sea la mayor de las deshumanizaciones ideada por el ser humano., pero al mismo tiempo es un recurso profundamente humano. Ser\u00eda imposible soportar el dolor que supone tomarse como algo personal todas las tragedias que sacuden el mundo. En definitiva, lo m\u00e1s humano, por terrible que pueda parecer, es tratar a esas v\u00edctimas por igual sin caer en la demagogia de acercarse a unas pocas y alejarse de ellas inmediatamente despu\u00e9s. Eso sirve, s\u00ed, para vender, pero no para hacernos m\u00e1s humanos. Vender no es malo; lo &#8220;malo&#8221; es no reconocerlo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hace ya tres semanas que el Airbus de Air France se estrell\u00f3 en el oc\u00e9ano Atl\u00e1ntico. 228 personas perecieron en un accidente de cuyas causas poco se sabe y por el que los medios ya han comenzado a olvidarse. Esto no es nada nuevo, pero es interesante exponer el modelo que se sigue para informar [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[15,27,351,733],"class_list":["post-84","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-accidente","tag-airbus","tag-humanizar","tag-tragedia"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/comments?post=84"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/84\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/media?parent=84"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/categories?post=84"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/tags?post=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}