{"id":67,"date":"2009-04-07T10:10:00","date_gmt":"2009-04-07T10:10:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/aletheia\/?p=67"},"modified":"2009-04-07T10:10:00","modified_gmt":"2009-04-07T10:10:00","slug":"puede-economia-salvar-mundo","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/aletheia\/2009\/04\/07\/puede-economia-salvar-mundo\/","title":{"rendered":"\u00bfPuede la econom\u00eda salvar el mundo?"},"content":{"rendered":"<p>Un bill\u00f3n de d\u00f3lares o 700.000 millones de euros; ayudas p\u00fablicas de dimensiones colosales a los bancos en dificultades; intervenciones estatales, y una mayor supervisi\u00f3n de los mercados. \u00c9sta es, en resumidas cuentas, la receta que los pol\u00edticos han ideado para salir  de la que dicen es la peor crisis desde la II Guerra Mundial. Que ya es decir. El mundo trabaja para salvar la econom\u00eda, pero \u00bfpuede \u00e9sta hacer algo m\u00e1s que dar cr\u00e9ditos, engrasar los mercados y estimular el consumo? En otras palabras, \u00bfpuede la econom\u00eda contribuir a hacer un mundo mejor?<br \/>\nLa econom\u00eda es una disciplina que trata de la administraci\u00f3n m\u00e1s eficaz de unos recursos que de por s\u00ed son escasos (obviamente, si sobrara de todo, no har\u00eda falta administrar nada). Etimol\u00f3gicamente, la palabra hace referencia a la gesti\u00f3n del hogar (&#8216;oikos&#8217;, en griego, quiere decir casa), pero por extensi\u00f3n, se puede hablar de la administraci\u00f3n de los recursos a cualquier nivel, desde el propio individuo hasta el estado. Para simplificar las cosas, centr\u00e9monos en el individuo, en cada uno de nosotros.<br \/>\nSupongamos que existe una forma de predecir el comportamiento del ser humano, una teor\u00eda que explique por qu\u00e9 las personas hacemos unas cosas y no otras. Hay algunos economistas que as\u00ed lo creen: es la teor\u00eda del comportamiento racional. Para entenderlo, basta con pensar en las compras. Todos efectuamos un c\u00e1lculo de lo que nos cuesta y de lo que nos ofrece un producto para tomar una decisi\u00f3n. Si los pros superan a los contras, lo adquirimos; si no, optamos por otro.<\/p>\n<p><IMG src=\"\/aletheia\/wp-content\/uploads\/sites\/7\" id=\"img_2\" class=\"imgcen\"><strong>M\u00e1s all\u00e1 del dinero<\/strong><br \/>\nEsta teor\u00eda, sin embargo, va m\u00e1s all\u00e1 del dinero y asegura que tambi\u00e9n puede explicar el comportamiento humano. Dicho de otra forma: todo lo que hacemos lo hacemos de acuerdo a incentivos.   Steven D. Levitt y Tim Harford son dos economistas que han hecho fortuna en su campo. Los \u00faltimos libros publicados por ambos \u2013\u2018Freakonomics\u2019 en el caso del primero, y \u2018El economista camuflado\u2019 y \u2018La l\u00f3gica oculta de la vida\u2019, en el del segundo- han sido todo un \u00e9xito explicando precisamente la teor\u00eda de los incentivos y del comportamiento racional. Preguntas como \u00bfpor qu\u00e9 se han incrementado las pr\u00e1cticas de sexo oral en Estados Unidos en los \u00faltimos a\u00f1os? o \u00bfpor qu\u00e9 delinquen los criminales? menudean en sus p\u00e1ginas para explicar que los incentivos no s\u00f3lo funcionan con el dinero.<br \/>\nDe acuerdo a esta teor\u00eda, la pr\u00e1ctica del sexo oral se ha incrementado porque las j\u00f3venes son m\u00e1s conscientes del peligro del SIDA y porque en el caso de abortar, algunos estados obligan a informar a los padres de ello. Se trata, por lo tanto, de un c\u00e1lculo: \u00bfmerece la pena el sexo \u2018convencional\u2019 si puede suponer el contagio del SIDA o que se enteren tus padres de lo que hacen con sus novios?  En cuanto a la delincuencia, esta teor\u00eda explica el crimen por un c\u00e1lculo entre lo que \u2013pongamos por caso- un ladr\u00f3n puede ganar en sus robos y la dureza del c\u00f3digo penal. A lo que parece, cuando la ley es dura, la tasa de criminalidad baja. O al menos hace pensar a los cacos que quiz\u00e1s no merezca del todo la pena robar si les espera una buena temporada entre rejas.<br \/>\nEstos son s\u00f3lo algunos de los muchos ejemplos que se podr\u00edan poner de la explicaci\u00f3n racional utilizada por los economistas. No quiere esto decir que sea la explicaci\u00f3n correcta o la \u00fanica posible; racional tampoco significa la mejor de las elecciones posibles. Las adicciones son un ejemplo de esto \u00faltimo. Bajo (casi) ninguna perspectiva es bueno fumar o beber alcohol, pero los que lo hacen siguen la teor\u00eda de la elecci\u00f3n racional, porque valoran m\u00e1s el placer que les proporciona que los beneficios que obtendr\u00edan de dejarlo.<\/p>\n<p><strong>Conclusi\u00f3n<\/strong><br \/>\nAs\u00ed las cosas, esta teor\u00eda busca explicar la conducta humana para poder preverla. Sabiendo por qu\u00e9 hacen las personas lo que hacen, los economistas pueden incentivar aquellas actividades que sean m\u00e1s beneficiosas. Los dos ejemplos se\u00f1alados \u2013el del sexo oral y el de los ladrones- pueden parecer c\u00f3micos, pero no lo son en absoluto: el primero aborda el espinoso tema de la educaci\u00f3n sexual y el aborto; el segundo, puede ofrecer pistas sobre el camino a seguir respecto a la delincuencia.\u00a0 <\/p>\n<div>La econom\u00eda no hace m\u00e1s que dar disgustos \u00faltimamente y los pol\u00edticos se han lanzado en su rescate. Son ciclos y terminar\u00e1 por recuperarse. Las tornas cambiar\u00e1n. De lo que se trata es de saber si su forma de analizar el mundo puede servir para mejorar \u00e9ste. Suponer que actuamos racionalmente es su apuesta para hacerlo.<\/p>\n<\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Un bill\u00f3n de d\u00f3lares o 700.000 millones de euros; ayudas p\u00fablicas de dimensiones colosales a los bancos en dificultades; intervenciones estatales, y una mayor supervisi\u00f3n de los mercados. \u00c9sta es, en resumidas cuentas, la receta que los pol\u00edticos han ideado para salir de la que dicen es la peor crisis desde la II Guerra Mundial. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[167,215,230,477,506,613,691,719],"class_list":["post-67","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-crisis","tag-economia","tag-eleccion","tag-mejor","tag-mundo","tag-racional","tag-soluciones","tag-teoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/67","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/comments?post=67"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/67\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/media?parent=67"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/categories?post=67"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/tags?post=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}