{"id":57,"date":"2009-02-24T07:29:00","date_gmt":"2009-02-24T07:29:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/aletheia\/?p=57"},"modified":"2009-02-24T07:29:00","modified_gmt":"2009-02-24T07:29:00","slug":"justicia-o-venganza","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/aletheia\/2009\/02\/24\/justicia-o-venganza\/","title":{"rendered":"\u00bfJusticia o venganza?"},"content":{"rendered":"<p><DIV style=\"TEXT-ALIGN: left\"><IMG class=imgcen id=img_0 src=\"\/aletheia\/wp-content\/uploads\/sites\/7\/sevilla.JPG\">&#8220;\u00a1Asesinos!&#8221;, gritan con ira los reunidos a las puertas de los juzgados cuando aparecen las huidizas figuras de los matarifes de Marta. &#8220;\u00a1Cadena perpetua!,\u00a1que sufran en la c\u00e1rcel!&#8221;, reclama la madre de la joven. &#8220;\u00a1Queremos justicia!&#8221;, concluyen todos ellos. La reacci\u00f3n de dolor ante casos como el de esta joven sevillana o al de Mariluz es perfectamente comprensible, pero cabe preguntarse si lo que se pide es justicia o m\u00e1s bien venganza. El sentido de las reformas legales que reclaman m\u00e1s bien hacen pensar en la segunda de las posibilidades, la del ojo por ojo y diente por diente. Tratar\u00e9 de ilustrar lo que quiero decir con una hermosa y tr\u00e1gica historia, la de la estirpe de Agamen\u00f3n.<\/p>\n<p>Agamen\u00f3n es el rey m\u00edtico que promovi\u00f3 la Guerra de Troya. Este cruel monarca, causante de la c\u00f3lera de Aquiles por negarle los m\u00e9ritos que se hab\u00eda ganado en el campo de batalla, tambi\u00e9n dio comienzo a una larga cadena de venganzas a la que s\u00f3lo la justicia, encarnada en la ley, pudo poner fin. A su regreso tras diez a\u00f1os de guerra, su mujer (Clitemestra) no hab\u00eda olvidado un terrible crimen: hab\u00eda sacrificado a la hija ambos, Ifigenia, para que la expedici\u00f3n hacia Troya pudiera partir. \u00bfQu\u00e9 hacer ante tal barbaridad? Vengarse del h\u00e9roe reci\u00e9n regresado. Ojo por ojo. \u00bfAcabar\u00eda aqu\u00ed el reguero de sangre iniciado por Agamen\u00f3n? No. Electra, la tr\u00e1gica Electra, quiere venganza y hace que su hermano Orestes comparta sus sentimientos. La venganza contin\u00faa y matan a su madre y a su amante, a la saz\u00f3n primo de Agamen\u00f3n.<\/p>\n<p><IMG class=imgizqda id=img_1 src=\"\/aletheia\/wp-content\/uploads\/sites\/7\">Ahora es Orestes el siguiente paso en este ciclo vicioso de acci\u00f3n y reacci\u00f3n. El hijo vengador teme a las Erinis, las personificaciones femeninas de la vendeta. Son ellas (Alecto -&#8216;Implacable&#8217;, Megera -&#8216;Seductora&#8217;- y, sobre todo, Tis\u00edfone -&#8216;Perseguidora de los delitos de sangre&#8217;-) las mejores representantes de esta arcaica forma de justicia, la de la sangre por la sangre. Orestes corre a protegerse en Atenas, donde la ley, la justicia, impedir\u00e1 que la cadena de venganzas contin\u00fae.<\/p>\n<p>Olvid\u00e9monos de los nombres y qued\u00e9monos con la clave de la historia. S\u00f3lo la ley, la justicia, puede poner fin a una cadena infinita de venganzas. Y las leyes no deben cambiarse en momentos de tanto dolor; requieren de un grado de reflexi\u00f3n y sosiego que no se da en estos momentos, especialmente entre los familiares de las v\u00edctimas. Como escribiera Ortega y Gasset, lo propio de la civilizaci\u00f3n es reducir la violencia al \u00faltimo recurso (un matiz: ni la violencia ni la venganza equivalen necesariamente a muerte, sino a castigos sin m\u00e1s fin que el castigo mismo). As\u00ed las cosas, cuando Zapatero reciba hoy a los padres de Marta, deber\u00eda tener en cuenta que, a la larga, la venganza no lleva a ning\u00fan sitio. Eso s\u00ed, el presidente deber\u00eda asegurarse de que la Justicia efectivamente funciona para que Tis\u00edfone no tenga siquiera la tentaci\u00f3n de volver a aparecer en escena.<\/p>\n<p>P.D. Lo mismo podr\u00eda decirse en los casos de terrorismo. Es perfectamente comprensible el dolor de las v\u00edctimas y la casi irreprimible reacci\u00f3n de desear a los asesinos el mismo destino que han dado a sus v\u00edctimas, pero esto s\u00f3lo llevar\u00eda a la insoportable espiral de violencia que narra la tragedia de Agamen\u00f3n. En otras palabras, a la hora de reformar las leyes, la palabra de las v\u00edctimas tiene que ser escuchada, s\u00ed, pero con mucha prudencia.<br \/>\n<\/DIV><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&#8220;\u00a1Asesinos!&#8221;, gritan con ira los reunidos a las puertas de los juzgados cuando aparecen las huidizas figuras de los matarifes de Marta. &#8220;\u00a1Cadena perpetua!,\u00a1que sufran en la c\u00e1rcel!&#8221;, reclama la madre de la joven. &#8220;\u00a1Queremos justicia!&#8221;, concluyen todos ellos. La reacci\u00f3n de dolor ante casos como el de esta joven sevillana o al de Mariluz [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[23,411,464,467,754,773],"class_list":["post-57","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-agamenon","tag-justicia","tag-marluz","tag-marta","tag-venganza","tag-zapatero"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/57\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/media?parent=57"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/categories?post=57"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/tags?post=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}