{"id":42,"date":"2008-11-02T15:13:15","date_gmt":"2008-11-02T15:13:15","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/aletheia\/?p=42"},"modified":"2008-11-02T15:13:15","modified_gmt":"2008-11-02T15:13:15","slug":"son-tan-diferentes","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/aletheia\/2008\/11\/02\/son-tan-diferentes\/","title":{"rendered":"\u00bfSon tan diferentes?"},"content":{"rendered":"<p><meta http-equiv=\"Content-Type\" content=\"text\/html; charset=utf-8\"><meta name=\"ProgId\" content=\"Word.Document\"><meta name=\"Generator\" content=\"Microsoft Word 11\"><meta name=\"Originator\" content=\"Microsoft Word 11\"><link rel=\"File-List\" href=\"file:\/\/\/C:%5CDOCUME%7E1%5CGaray%5CCONFIG%7E1%5CTemp%5Cmsohtml1%5C01%5Cclip_filelist.xml\"><!--[if gte mso 9]><xml>  <w:WordDocument>   <w:View>Normal<\/w:View>   <w:Zoom>0<\/w:Zoom>   <w:HyphenationZone>21<\/w:HyphenationZone>   <w:PunctuationKerning\/>   <w:ValidateAgainstSchemas\/>   <w:SaveIfXMLInvalid>false<\/w:SaveIfXMLInvalid>   <w:IgnoreMixedContent>false<\/w:IgnoreMixedContent>   <w:AlwaysShowPlaceholderText>false<\/w:AlwaysShowPlaceholderText>   <w:Compatibility>    <w:BreakWrappedTables\/>    <w:SnapToGridInCell\/>    <w:WrapTextWithPunct\/>    <w:UseAsianBreakRules\/>    <w:DontGrowAutofit\/>   <\/w:Compatibility>   <w:BrowserLevel>MicrosoftInternetExplorer4<\/w:BrowserLevel>  <\/w:WordDocument> <\/xml><![endif]--><!--[if gte mso 9]><xml>  <w:LatentStyles DefLockedState=\"false\" LatentStyleCount=\"156\">  <\/w:LatentStyles> <\/xml><![endif]--><\/p>\n<style> <!--  \/* Style Definitions *\/  p.MsoNormal, li.MsoNormal, div.MsoNormal {mso-style-parent:\"\"; margin:0cm; margin-bottom:.0001pt; mso-pagination:widow-orphan; font-size:12.0pt; font-family:\"Times New Roman\"; mso-fareast-font-family:\"Times New Roman\";} @page Section1 {size:595.3pt 841.9pt; margin:70.85pt 3.0cm 70.85pt 3.0cm; mso-header-margin:35.4pt; mso-footer-margin:35.4pt; mso-paper-source:0;} div.Section1 {page:Section1;} --> <\/style>\n<p><!--[if gte mso 10]> \n\n<style>  \/* Style Definitions *\/  table.MsoNormalTable {mso-style-name:\"Tabla normal\"; mso-tstyle-rowband-size:0; mso-tstyle-colband-size:0; mso-style-noshow:yes; mso-style-parent:\"\"; mso-padding-alt:0cm 5.4pt 0cm 5.4pt; mso-para-margin:0cm; mso-para-margin-bottom:.0001pt; mso-pagination:widow-orphan; font-size:10.0pt; font-family:\"Times New Roman\"; mso-ansi-language:#0400; mso-fareast-language:#0400; mso-bidi-language:#0400;} <\/style>\n\n <![endif]-->  <\/p>\n<p class=\"MsoNormal\">El martes se dilucida finalmente qui\u00e9n ser\u00e1 el presidente de los Estados Unidos. Ya era hora tras una larg\u00edsima campa\u00f1a electoral y una no menos intensa lucha por las primarias en el partido dem\u00f3crata. \u00bfGanar\u00e1 el \u00eddolo de masas (europeas, por lo que traslucen los medios de comunicaci\u00f3n del Viejo Continente) Obama o lo har\u00e1 McCain? \u00bfSon realmente tan diferentes?<\/p>\n<p class=\"MsoNormal\">A primera vista, desde luego que s\u00ed. Obama, con un nombre tan publicitario, posible primer presidente negro, culto,<span style=\"\"> <\/span>especialista en recaudar fondos para la campa\u00f1a (incluso ha introducido propaganda en videojuegos), candidato del cambio, el nuevo Kennedy\u2026; y McCain, viejo h\u00e9roe de guerra, mand\u00edbula cuadrada de militar, actitud r\u00edgida, pero m\u00e1s ligado a la herencia de Bush.<\/p>\n<p class=\"MsoNormal\">Sin embargo, no creo que la diferencia sea tal. Existe una realidad por encima de todo candidato y es el propio poder de los Estados Unidos: el imperio. M\u00e1s all\u00e1 de las posturas de uno u otro, ninguno dejar\u00e1 que el poder de su pa\u00eds meng\u00fce en el mundo y para ello, har\u00e1n lo que sea necesario. El venerado Clinton lo hizo en su momento y, si es necesario, lo har\u00e1 Obama (si, como parece, sale vencedor). El sistema est\u00e1 por encima de las personas y Obama pertenece tanto o m\u00e1s que McCain al mismo. El primero representa a la clase ilustrada educada en las mejores universidades, como el idolatrado Kennedy, y el segundo representa m\u00e1s a la Am\u00e9rica profunda ligada al ej\u00e9rcito y a las ideas simples. Los dos ingredientes fundamentales de Estados Unidos, pero tan pertenecientes al sistema el uno como el otro.<\/p>\n<p class=\"MsoNormal\">Dec\u00eda Noam Chomsky en &#8216;Repensando Camelot&#8217; que la \u00fanica diferencia entre Kennedy y Lyndon Johnson era la afecci\u00f3n que consigui\u00f3 el primero por parte de la intelectualidad. Tipo culto y elegante frente al \u201ccampesino\u201d que fue su vicepresidente y sucesor. Los hechos, sin embargo, demuestran que el uno y el otro vinieron a hacer lo mismo, especialmente en la guerra de Vietnam. Por eso, la conclusi\u00f3n de mi no muy admirado Chomsky es que dem\u00f3cratas y republicanos son realmente dos alas de un mismo partido, y no dos partidos. Y lo mismo vino a decir Ralph Nader en las elecciones de 2000: la \u00fanica diferencia entre Gore y Bush es la velocidad a la que se inclinan ante las multinacionales.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El martes se dilucida finalmente qui\u00e9n ser\u00e1 el presidente de los Estados Unidos. Ya era hora tras una larg\u00edsima campa\u00f1a electoral y una no menos intensa lucha por las primarias en el partido dem\u00f3crata. \u00bfGanar\u00e1 el \u00eddolo de masas (europeas, por lo que traslucen los medios de comunicaci\u00f3n del Viejo Continente) Obama o lo har\u00e1 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[131,231,248,471,537,743],"class_list":["post-42","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-chomsky","tag-elecciones","tag-estados","tag-mccain","tag-obama","tag-unidos"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/comments?post=42"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/42\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/media?parent=42"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/categories?post=42"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/tags?post=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}