{"id":36,"date":"2008-04-17T13:46:03","date_gmt":"2008-04-17T13:46:03","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/aletheia\/?p=36"},"modified":"2008-04-17T13:46:03","modified_gmt":"2008-04-17T13:46:03","slug":"lo-importante-y-accesorio","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/aletheia\/2008\/04\/17\/lo-importante-y-accesorio\/","title":{"rendered":"Lo importante y lo accesorio"},"content":{"rendered":"<p>Tres hechos sucedidos recientemente empujan a una reflexi\u00f3n com\u00fan acerca de lo que es importante y de lo que es accesorio: la visita de Sarkozy a Inglaterra, la composici\u00f3n del nuevo gobierno de Jos\u00e9 Luis Rodr\u00edguez Zapatero y la presencia de Angela Merkel en la inauguraci\u00f3n de la \u00f3pera de Oslo.<br \/>\nA finales de marzo, Nicolas Sarkozy llev\u00f3 a cabo una importante visita de estado a Inglaterra. Su presencia ten\u00eda una gran importancia, pues pod\u00eda significar -seg\u00fan los analistas- una reorientaci\u00f3n del n\u00facleo central de la Uni\u00f3n Europea incorporando a los tradicionalmente esc\u00e9pticos isle\u00f1os. Adem\u00e1s, la historia recuerda que las relaciones entre ambas potencias nunca han sido especialmente amistosas (Guerra de los Cien a\u00f1os, Napole\u00f3n&#8230;). Sin embargo, los focos no se centraron en estos hechos, sino en el presunto brillo de la primer dama francesa, la ya archiconocida Carla Bruni. No parece de recibo que una visita de estado de semejante calibre se diluya con temas de coraz\u00f3n, con su elegancia&#8230; Lo importante y lo accesorio.<\/p>\n<p>Ya se conoce el nuevo gobierno de Zapatero y todas las miradas se han centrado en su composici\u00f3n. Nueve mujeres ser\u00e1n mayor\u00eda en los diecisiete ministerios de esta nueva legislatura con una de ellas, para m\u00e1s inri en estado de buenaesperanza, a la cabeza de la marcial cartera de defensa. Adem\u00e1s, se ha creado un ministerio de Igualdad que tiene como fin precisamente garantizar la igualdad de oportunidades entre hombres y mujeres. Todos los peri\u00f3dicos recog\u00edan, ya el martes d\u00eda 15, la foto de Carme Chac\u00f3n pasando revista a las tropas. Sin embargo, no se llev\u00f3 a las portadas las m\u00e1s que interesantes intenciones de Cristina Garmendia, la nueva ministra de Ciencia e Innovaci\u00f3n, que se ha propuesto enterrar el unamuniano esp\u00edritu del &#8220;que inventen ellos&#8221;; las declaraciones de Celestino Corbacho, ministro de Trabajo e Inmigraci\u00f3n, ligando la presencia de inmigrantes al ejercicio de un trabajo, o la necesaria reorentaci\u00f3n de la econom\u00eda desde la construcci\u00f3n al sector tecnol\u00f3gico y ligado a la innovaci\u00f3n. Lo importante y lo accesorio.<\/p>\n<p>Por \u00faltimo, el mismo d\u00eda que se publicaba la ya &#8220;hist\u00f3rica&#8221; foto de Chac\u00f3n se le daba una gran relevancia a otra foto: la de la canciller alemana, Angela Merkel, luciendo un generoso escote en la inauguraci\u00f3n de la \u00f3pera de Oslo. Todos los medios se muestran anonadados ante un cambio tan radical en una mujer tan pacata, pero quiz\u00e1s sea m\u00e1s importante fijarse en otras de sus actuaciones para que el motor econ\u00f3mico de Europa reencuentre el camino de la prosperidad. Lo importante y lo accesorio.<\/p>\n<p>Todas estas noticias tienen en com\u00fan la presencia de mujeres en puestos de relevancia. Pero lo importante es que sean competentes, no que sean mujeres. Lo importante y lo accesorio.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Tres hechos sucedidos recientemente empujan a una reflexi\u00f3n com\u00fan acerca de lo que es importante y de lo que es accesorio: la visita de Sarkozy a Inglaterra, la composici\u00f3n del nuevo gobierno de Jos\u00e9 Luis Rodr\u00edguez Zapatero y la presencia de Angela Merkel en la inauguraci\u00f3n de la \u00f3pera de Oslo. A finales de marzo, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[169,368,502,533],"class_list":["post-36","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-criterio","tag-importancia","tag-mujer","tag-noticias"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/comments?post=36"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/36\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/media?parent=36"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/categories?post=36"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/tags?post=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}