{"id":29,"date":"2008-03-19T14:23:16","date_gmt":"2008-03-19T14:23:16","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/aletheia\/?p=29"},"modified":"2008-03-19T14:23:16","modified_gmt":"2008-03-19T14:23:16","slug":"vacaciones-y-sociedad-servicios","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/aletheia\/2008\/03\/19\/vacaciones-y-sociedad-servicios\/","title":{"rendered":"Vacaciones y sociedad de servicios"},"content":{"rendered":"<p>Resulta que las vacaciones de Semana Santa de este a\u00f1o hacen que durante tres d\u00edas (desde el mi\u00e9rcoles hasta el viernes) el pa\u00eds est\u00e9 cuasi paralizado. En una entrada anterior ya escrib\u00ed sobre la necesidad de escalonar las fiestas y evitar que todos tengamos las vacaciones al mismo tiempo. Todos debemos descansar, pero si lo hici\u00e9ramos m\u00e1s racionalmente, todo seguir\u00eda funcionando de una manera m\u00e1s o menos normal. \u00bfEs de recibo que no se puedan hacer compras -y me refiero a comida, no a ropa o art\u00edculos accesorios- durante tantos d\u00edas? \u00bfPor qu\u00e9 el Eroski no ha podido abrir al menos un d\u00eda como era su deseo? Los peque\u00f1os comerciantes apelan al derecho de todos al descanso; pero se trata -evidentemente- de proteger sus intereses econ\u00f3micos. \u00bfAcaso el d\u00eda 24 y 31 de diciembre no abren hasta bien entrada la tarde? \u00bfPor qu\u00e9 no descansar entonces? Las ventas, claro. <\/p>\n<p> Sin embargo, por mucho que se esfuercen, tienen todas las de perder por una cuesti\u00f3n de puro n\u00famero: ellos son pocos y los consumidores, muchos. Los lamentables horarios de trabajo hacen que precisamente aquellos d\u00edas en que la mayor\u00eda libra, los comercios cierran. Ello trae al menos dos consecuencias: la primera, que no se pueden hacer las compras con tranquilidad, y la segunda, el perjuicio para una econom\u00eda basada en gran parte en el consumo privado. A no mucho tardar y como sucede en Madrid, los horarios se liberalizar\u00e1n pese a quien pese.<\/p>\n<p> Adem\u00e1s de los comercios, \u00bfpor qu\u00e9 cierran polideportivos, bibliotecas, universidad e incluso ayuntamientos? \u00bfPor qu\u00e9 no poder hacer deporte, leer, estudiar o acudir a la casa consistorial cualquier d\u00eda de la semana? Recordemos -otra vez- que vivimos en una sociedad de servicios. Insisto, bastar\u00eda un poco de l\u00f3gica para que esta sinraz\u00f3n pasase a mejor vida. \u00a1Abran, por favor, aunque sea s\u00f3lo por la ma\u00f1ana!<\/p>\n<p> Aletheia<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Resulta que las vacaciones de Semana Santa de este a\u00f1o hacen que durante tres d\u00edas (desde el mi\u00e9rcoles hasta el viernes) el pa\u00eds est\u00e9 cuasi paralizado. En una entrada anterior ya escrib\u00ed sobre la necesidad de escalonar las fiestas y evitar que todos tengamos las vacaciones al mismo tiempo. Todos debemos descansar, pero si lo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-29","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/comments?post=29"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/29\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/media?parent=29"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/categories?post=29"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/tags?post=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}