{"id":184,"date":"2011-01-28T10:36:00","date_gmt":"2011-01-28T10:36:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/aletheia\/?p=184"},"modified":"2011-01-28T10:36:00","modified_gmt":"2011-01-28T10:36:00","slug":"25-anos-del-desastre-del-challenger","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/aletheia\/2011\/01\/28\/25-anos-del-desastre-del-challenger\/","title":{"rendered":"25 a\u00f1os del desastre del Challenger"},"content":{"rendered":"<p><IMG src=\"\/aletheia\/wp-content\/uploads\/sites\/7\" id=\"img_0\" class=\"imgcen\">Hoy se cumplen 25 a\u00f1os de la tragedia del Challenger. El 28 de enero de 1986 este transbordador despegaba desde Florida. Su vuelo s\u00f3lo dur\u00f3 73 segundos. El mundo entero contempl\u00f3 en directo la explosi\u00f3n que acab\u00f3 con la vida de los siete tripulantes y con parte del prestigio de la NASA. Para tratar de resta\u00f1ar el da\u00f1o, el presidente Reegan estableci\u00f3 una comisi\u00f3n de investigaci\u00f3n que aclarara las causas y evitara un nuevo desastre. \u2018Comisi\u00f3n Rogers\u2019, la llamaron, porque a la cabeza estaba William P. Rogers, que hab\u00eda sido secretario de Estado en la Administraci\u00f3n Nixon. Entre los once miembros restantes estaban Neil Armstrong, David Acheson (hijo de Dan Acheson, exsecretario de Estado) el general Donald Kutyna o el Premio Nobel de F\u00edsica <A href=\"http:\/\/blogs.elcorreo.com\/aletheia\/2010\/5\/3\/el-nobel-fisica-deficiente-mental-comia-bares-de\" title=\"http:\/\/blogs.elcorreo.com\/aletheia\/2010\/5\/3\/el-nobel-fisica-deficiente-mental-comia-bares-de\" id=\"link_0\">Richard Feynman<\/a>.<\/p>\n<p><IMG src=\"\/aletheia\/wp-content\/uploads\/sites\/7\" id=\"img_0\" class=\"imgizqda\">Seguramente el episodio m\u00e1s recordado de aquella investigaci\u00f3n fue la rueda de prensa en la que Feynman introdujo una de las juntas del transbordador en un vaso de agua helada para demostrar la causa del accidente: la congelaci\u00f3n de esa pieza desencaden\u00f3 un serie de efectos que acabaron destruyendo la nave. El propio Feynman cuenta en el libro \u2018What do you care what other people think?\u2019 c\u00f3mo dio con la soluci\u00f3n y c\u00f3mo prepar\u00f3 el experimento. Curiosamente la idea no fue suya, sino del general Kutyna, que adem\u00e1s de militar era graduado en aeron\u00e1utica por el MIT. Ya desde el principio estos dos personajes hicieron buenas migas. De hecho, en la primera rueda de prensa de la comis\u00f3n, en la que estaban sentados juntos, Kutyna se acerc\u00f3 a Feynman y le dijo: \u201cCopiloto a piloto: p\u00e9inate\u201d. Y el cient\u00edfico respondi\u00f3: \u201c\u00bfMe prestas tu peine?\u201d. <\/p>\n<p> An\u00e9cdotas al margen, un d\u00eda el general le record\u00f3 a Feynman que la temperatura el d\u00eda del despegue era de 28-29 grados Farenheit cuando la temperatura m\u00e1s fr\u00eda hasta ese momento hab\u00eda sido de 53 (traducido a grados Celsius ser\u00edan -2 y 11 respectivamente). Inmediatamente el f\u00edsico se dio cuenta de lo que hab\u00eda ocurrido y empez\u00f3 a preparar su demostraci\u00f3n. Y para estar seguro de su efecto, lo prob\u00f3 antes de hacerlo ante los medios. \u201cAunque sab\u00eda que ser\u00eda m\u00e1s dram\u00e1tico y honesto hacer el experimento por primera vez en la comparecencia p\u00fablica, hice algo de lo que me averg\u00fcenzo un poco. Hice trampa. No lo pude resistir. Lo ensay\u00e9\u201d.<\/p>\n<p> La historia no termin\u00f3 aqu\u00ed. Resulta que en todas las comparecencias anteriores todos ten\u00eda un vaso de agua fr\u00eda a su disposici\u00f3n. Pero no en esta ocasi\u00f3n. Feynman inmediatamente pidi\u00f3 uno para \u00e9l; de ello depend\u00eda todo su argumento. Avanzaba la comparecencia y el agua que no llegaba. Cuando lleg\u00f3, result\u00f3 que no s\u00f3lo la tra\u00edan para \u00e9l, sino para todos. De ah\u00ed la tardanza. Finalmente pudo hacer su demostraci\u00f3n y una de las claves del desastre qued\u00f3 demostrada.<\/p>\n<p> En el fondo de la tragedia estuvieron las discrepancias entre lo que ped\u00edan los administradores, impulsados por las urgencias de los pol\u00edticos, y lo que los ingenieros realmente pod\u00edan hacer. El ejemplo m\u00e1s claro est\u00e1 en las estimaciones que unos y otros ten\u00edan sobre las posibilidades de un error fatal en los lanzamientos. Mientras los segundos lo situaban en un 1%, para los primeros era de uno por mil. De ser cierta esta \u00faltima, se hubiera podido lanzar un transbordador cada d\u00eda durante 300 a\u00f1os con la esperanza de perder s\u00f3lo uno. <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy se cumplen 25 a\u00f1os de la tragedia del Challenger. El 28 de enero de 1986 este transbordador despegaba desde Florida. Su vuelo s\u00f3lo dur\u00f3 73 segundos. El mundo entero contempl\u00f3 en directo la explosi\u00f3n que acab\u00f3 con la vida de los siete tripulantes y con parte del prestigio de la NASA. Para tratar de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[127,143,185,265,273,341,646],"class_list":["post-184","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-challenger","tag-comision","tag-desastre","tag-explosion","tag-feynman","tag-hielo","tag-rogers"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/comments?post=184"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/184\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/media?parent=184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/categories?post=184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/tags?post=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}