{"id":183,"date":"2010-12-29T10:47:00","date_gmt":"2010-12-29T10:47:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/aletheia\/?p=183"},"modified":"2010-12-29T10:47:00","modified_gmt":"2010-12-29T10:47:00","slug":"hombre-tienes-elegir-mujeres-o-vino","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/aletheia\/2010\/12\/29\/hombre-tienes-elegir-mujeres-o-vino\/","title":{"rendered":"Hombre, tienes que elegir: \u00bfmujeres o alcohol?"},"content":{"rendered":"<p><IMG id=\"img_0\" class=\"imgizqda\" src=\"\/aletheia\/wp-content\/uploads\/sites\/7\">La Asociaci\u00f3n Americana de Economistas del Vino (s\u00ed, al parecer, existe una asociaci\u00f3n tal y tiene su propia p\u00e1gina web, <A href=\"http:\/\/www.wine-economics.org\">www.wine-economics.org<\/a>) ha publicado un trabajo que pone al hombre ante una terrible disyuntiva: \u00bfmujeres -en plural- o alcohol? Mara Squicciarini y Johan Swinnen, los autores del <A href=\"http:\/\/www.wine-economics.org\/workingpapers\/AAWE_WP75.pdf\" title=\"http:\/\/www.wine-economics.org\/workingpapers\/AAWE_WP75.pdf\" id=\"link_0\">estudio<\/a>, cayeron en la cuenta de un hecho singular que relaciona a musulmanes y mormones: ambas sociedades son pol\u00edgamas y no permiten el consumo de alcohol. \u00bfEs esto una simple casualidad o hay algo m\u00e1s?<\/p>\n<p>Y es que si miramos al pasado de cierta manera, resulta que pudiera haber una correlaci\u00f3n entre el paso de una sociedad de la poligamia a la monogamia y un aumento del consumo de alcohol. \u00bfY qu\u00e9 es una correlaci\u00f3n? Antes de decir lo que es, es todav\u00eda m\u00e1s importante decir lo que no es, una causa. Que dos fen\u00f3menos est\u00e9n correlacionados quiere decir \u00fanicamente que cuando uno se da, se da tambi\u00e9n el otro, sin que esto signifique que uno sea la causa de otro. Para lo que aqu\u00ed interesa, esto quiere decir que los autores no sostienen que el alcohol empuje a la monogamia o que la monogamia implique -ni por desesparaci\u00f3n ni por ninguna otra raz\u00f3n- un mayor consumo de alcohol. Simplemente constatan que las sociedades mon\u00f3gamas consumen m\u00e1s alcohol que las pol\u00edgamas sin establecer qu\u00e9 causa qu\u00e9. \u00bfY por qu\u00e9 sucede esto? Porque hay causas subyacentes que afectan tanto a los matrimonios como al consumo de alcohol.<\/p>\n<p>En el caso de las sociedades pre-industriales encuentran una raz\u00f3n econ\u00f3mica detr\u00e1s de esta relaci\u00f3n. Entre \u00e9stas, las que se dedicaban a la caza, pesca y recolecci\u00f3n tend\u00edan a la monogamia porque sus recursos eran inferiores a las que se dedicaban a la agricultura, de manera que un hombre dif\u00edcilmente pod\u00eda sostener a m\u00e1s de una mujer. Y no es que no aspirasen a m\u00e1s, es que sencillamente su ecolog\u00eda, el medio en el que subsist\u00edan, no se lo permit\u00eda (por eso se le llama \u2018monogamia impuesta por la ecolog\u00eda\u2019). Otra posible explicaci\u00f3n es la \u2018teor\u00eda de la defensa de los recursos\u2019, que sostiene que la poligamia es una estrategia reproductiva adaptada a situaciones en que el var\u00f3n-macho puede defender sus recursos (territorio, dinero&#8230;). En este caso, para la hembra ser\u00eda mejor compartir los bienes de un hombre rico con otras mujeres que arriesgarse a \u2018monopolizar\u2019 los de uno pobre.<\/p>\n<p>\u00bfY por qu\u00e9 unas beber\u00edan m\u00e1s alcohol que otros? Aqu\u00ed se abren dos hip\u00f3tesis: una, para sobrellevar las dificultades de una existencia que se supone m\u00e1s dificultosa (tradicionalmente se ha defendido que el paso a la agricultura supuso un paso adelante en el bienestar, pero se est\u00e1 discutiendo tambi\u00e9n esta asunci\u00f3n) y, dos, porque las sociedades de cazadores carecen de la estructuraci\u00f3n social y jerarqu\u00eda de las agr\u00edcolas, menos permisivas en general con este tipo de excesos. As\u00ed se explicar\u00eda la en principio sorprendente afirmaci\u00f3n de que las sociedades mon\u00f3gamas beban m\u00e1s alcohol que las pol\u00edgamas.<strong> <\/p>\n<p>La Revoluci\u00f3n Industrial<\/p>\n<p><\/strong>\u00bfC\u00f3mo se ha tramado hist\u00f3ricamente esta sorprendente relaci\u00f3n? Seg\u00fan los autores del estudio, la primera sociedad que impuso la monogamia fue la Grecia cl\u00e1sica. Y como es bien sabido, el vino forma parte indisoluble de la cultura mediterr\u00e1nea. Roma continu\u00f3 esta tendencia y la extendi\u00f3 por todo su territorio, una herencia que el cristianismo convertir\u00eda en sacramento. (Un peque\u00f1o alto en el camino. La inmensa mayor\u00eda de los mam\u00edferos son, por cuestiones de ventaja reproductiva, pol\u00edgamos. \u00bfPor qu\u00e9 la humanidadel gir\u00f3 hacia la ahora casi universal monogamia? Squicciarini y Swinnen sostienen, apoy\u00e1ndose en otros autores, que esta \u00faltima encierra una estrategia de estabilizaci\u00f3n social al ser una forma de organizaci\u00f3n m\u00e1s igualitaria. Dicho m\u00e1s claramente, es una simple cuesti\u00f3n de n\u00famero: dado que aproximadamente la proporci\u00f3n de hombre-mujer es 1 a 1, si un hombre tiene cuatro esposas, hay tres que no tienen ninguna, lo cual no suele ser una buena noticia para los perjudicados. La monogamia, es decir, el reparto de mujeres, aliviar\u00eda en gran forma esa tensi\u00f3n social y ayudar\u00eda a cohesionar el grupo. Aqu\u00ed, el hecho de que fuera la cuna de la democracia la primera en apostar por esta estrategia refuerza la hip\u00f3tesis del igualitarismo).<\/p>\n<p>La consolidaci\u00f3n definitiva tanto de la monogamia como del consumo del alcohol se dar\u00eda con la Revoluci\u00f3n Industrial. Nuevamente una confabulaci\u00f3n de factores sociales, econ\u00f3micos y tecnol\u00f3gicos hicieron que monogamia y alcohol aparecieran de la mano. Uno de los cambios introducidos por aquel despertar de Inglaterra fue el hecho de que la riqueza empez\u00f3 a proceder cada vez m\u00e1s del capital humano, del trabajo, y menos de la posesi\u00f3n de tierra. Ya es casualidad, pero en paralelo, el consumo de alcohol se dispar\u00f3 por su bajo precio y por las duras condiciones que deb\u00edan afrontar los trabajadores en las insalubres ciudades de la industralizaci\u00f3n. Y beber en demas\u00eda afecta a la productividad y, por lo tanto, a la riqueza de los hombres. Sin que una cause la otra, alcohol y monogamia aparecen de nuevo juntas.<\/p>\n<p>De ser cierto todo esto, t\u00fa, hombre, tienes que elegir: \u00bfcervezas o mujeres? Mormones y musulmanes ya han decidido.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La Asociaci\u00f3n Americana de Economistas del Vino (s\u00ed, al parecer, existe una asociaci\u00f3n tal y tiene su propia p\u00e1gina web, www.wine-economics.org) ha publicado un trabajo que pone al hombre ante una terrible disyuntiva: \u00bfmujeres -en plural- o alcohol? Mara Squicciarini y Johan Swinnen, los autores del estudio, cayeron en la cuenta de un hecho singular [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31,252,496,503,508,759],"class_list":["post-183","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-alcohol","tag-estudio","tag-mormones","tag-mujeres","tag-musulmanes","tag-vino"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/comments?post=183"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/183\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/media?parent=183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/categories?post=183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/tags?post=183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}