{"id":176,"date":"2010-10-18T10:17:00","date_gmt":"2010-10-18T10:17:00","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/aletheia\/?p=176"},"modified":"2010-10-18T10:17:00","modified_gmt":"2010-10-18T10:17:00","slug":"imprudentes-dijo-obama","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/aletheia\/2010\/10\/18\/imprudentes-dijo-obama\/","title":{"rendered":"&#039;Imprudentes&#039;, dijo Obama"},"content":{"rendered":"<p><IMG src=\"\/aletheia\/wp-content\/uploads\/sites\/7\" id=\"img_0\" class=\"imgizqda\">Hace poco menos de un mes se conoci\u00f3 la noticia de que Larry Summers, principal asesor econ\u00f3mico de Obama, dejaba su cargo. El presidente norteamericano, ocupado ahora en la campa\u00f1a de elecciones al Congreso en el ecuador de su mandato, se ha forjado una imagen de l\u00e1tigo acusador de los excesos financieros de Wall Street. \u201cImprudentes\u201d, les dijo a los banqueros al tiempo que hac\u00eda referencia al hombre alto que estaba a su espalda. Ese hombre alto era Paul Volcker, ex presidende la Reserva Federal y muy poco amigo de las innovaciones financieras desarrolladas por el sector en los \u00faltimos a\u00f1os. \u201cLa \u00fanica innovaci\u00f3n bancaria realmente \u00fatil han sido los cajeros autom\u00e1ticos\u201d, ha llegado a afirmar el hombre que intimidaba con su sola presencia (mide dos metros) a Alan Greenspan. De hecho, una de sus propuestas, conocida como \u2018Plan Volcker\u2019, es impedir a los bancos el tipo de inversiones especulativas que, en su opini\u00f3n, han sido claves para la crisis actual. Volcker se ha mostrado partidario adem\u00e1s de volver, aunque sea parcialmente, a la Ley Glass-Steagall, creada en 1933 por Roosevelt y que separaba la banca de inversi\u00f3n de la banca comercial con la intenci\u00f3n de reducir los riesgos que pod\u00edan tomar los banqueros tradicionales con los fondos de sus clientes.<\/p>\n<p>\u00bfY qu\u00e9 tiene que ver con todo esto Larry Summers? Pues que este hombre, un superdotado que entr\u00f3 con 16 a\u00f1os en el MIT y sobrino de dos Premios Nobel de Econom\u00eda (Paul Samuelson y Kenneth Arrow), apoy\u00f3 en 1999 la abolici\u00f3n de la citada ley de bancos cuando era secretario del Tesoro en la Administraci\u00f3n Clinton. Esto es lo que ha permitido que los bancos \u2018normales\u2019 puedan entrar en el negocio de las inversiones especulativas que tan da\u00f1inas han demostrado ser. Visto desde la distancia, Obama ten\u00eda en su equipo de asesores a dos hombres que pensaban justo lo contrario respecto a la innovaciones financieras y el papel de Wall Street. \u00bfC\u00f3mo calificar a los banqueros de imprudentes cuando uno de tus principales asesores ha sido uno de sus principales consejeros? <\/p>\n<p>Cuando en noviembre de 2008 Obama anunci\u00f3 la composici\u00f3n de su equipo econ\u00f3mico, los medios no parecieron interesados en esta contradicci\u00f3n. <A href=\"http:\/\/www.cincodias.com\/articulo\/economia\/Summers-tercera-baja-equipo-economico-Obama\/20100922cdscdseco_1\/cdseco\/\" title=\"http:\/\/www.cincodias.com\/articulo\/economia\/Summers-tercera-baja-equipo-economico-Obama\/20100922cdscdseco_1\/cdseco\/\" id=\"link_0\">Cinco D\u00edas<\/a> se\u00f1al\u00f3 que el nombramiento de Summers mandaba \u201cel mensaje de que la Casa Blanca tendr\u00e1 un pol\u00edtica centrista pero agresiva\u201d, pero no entr\u00f3 en mayores detalles. En <A href=\"http:\/\/www.elpais.com\/articulo\/internacional\/Obama\/promete\/fuerte\/inversion\/publica\/crisis\/elpepiint\/20081125elpepiint_5\/Tes)\" title=\"http:\/\/www.elpais.com\/articulo\/internacional\/Obama\/promete\/fuerte\/inversion\/publica\/crisis\/elpepiint\/20081125elpepiint_5\/Tes)\" id=\"link_1\">El Pa\u00eds<\/a> se se\u00f1al\u00f3 que Obama sumaba \u201csu autoridad (la de Summers) como una de las mejores cabezas econ\u00f3micas del pa\u00eds\u201d y en un peque\u00f1o despiece sobre este economista, se hac\u00eda menci\u00f3n a su pasado en el MIT, Harvard y en la administraci\u00f3n Clinton, pero no su apoyo a la abolici\u00f3n de la Ley Glass-Steagall (En su favor hay que decir que cuando Summers sali\u00f3 del Gobierno, s\u00ed apunt\u00f3 que el ala izquierda que apoyaba a Obama <A href=\"http:\/\/www.elpais.com\/articulo\/internacional\/Summers\/principal\/asesor\/economico\/Obama\/anuncia\/retirada\/elpepuint\/20100922elpepuint_2\/Tes\" title=\"http:\/\/www.elpais.com\/articulo\/internacional\/Summers\/principal\/asesor\/economico\/Obama\/anuncia\/retirada\/elpepuint\/20100922elpepuint_2\/Tes\" id=\"link_5\">no hab\u00eda visto con buenos ojos a este economista<\/a>). <A href=\"http:\/\/www.elcorreo.com\/vizcaya\/20081123\/mundo\/obama-elige-geithner-secretario-200811230503.html\" title=\"http:\/\/www.elcorreo.com\/vizcaya\/20081123\/mundo\/obama-elige-geithner-secretario-200811230503.html\" id=\"link_2\">El Correo<\/a> no dijo nada al respecto. Un poco m\u00e1s acertado estuvo <A href=\"http:\/\/www.expansion.com\/2010\/01\/22\/opinion\/llave-online\/1264191599.html\" title=\"http:\/\/www.expansion.com\/2010\/01\/22\/opinion\/llave-online\/1264191599.html\" id=\"link_3\">Expansi\u00f3n<\/a>, que si bien en un primer momento  no hizo alusi\u00f3n al guna al pasado de Summers, si mencion\u00f3 las posibles tiranteces entre Volcker y el d\u00fao Geithner-Summers cuando se present\u00f3 el plan para volver a regular el sector bancario. Inclsuo se record\u00f3 que fue la Administraci\u00f3n Clinton la que derog\u00f3 la Ley Glass-Steagall, si bien no llega a relacionar a Summers con este hecho.<\/p>\n<p>Evidentemente, no es imposible que Summers cambiara de opini\u00f3n en los diez a\u00f1os que permaneci\u00f3 al margen del gobierno. El <A href=\"http:\/\/www.nytimes.com\/2007\/06\/10\/magazine\/10wwln-summers-t.html?pagewanted=3&#038;ref=lawrence_h_summers\" title=\"http:\/\/www.nytimes.com\/2007\/06\/10\/magazine\/10wwln-summers-t.html?pagewanted=3&#038;ref=lawrence_h_summers\" id=\"link_4\">New York Times<\/a>  public\u00f3 en 2007 un art\u00edculo que hac\u00eda alusi\u00f3n a la evoluci\u00f3n de Summers desde unas posiciones no intervencionistas a otras m\u00e1s favorables a la regulaci\u00f3n. Pero los medios, incluso los especializados, no parecieron prestar atenci\u00f3n a un detalle que es, creo, m\u00e1s que un detalle. Al fin y al cabo, la Administraci\u00f3n Obama, llamada a acabar con los desmanes de la banca, ten\u00eda entre sus principales cerebros a quien hab\u00eda dado v\u00eda libre a dichos desmanes.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hace poco menos de un mes se conoci\u00f3 la noticia de que Larry Summers, principal asesor econ\u00f3mico de Obama, dejaba su cargo. El presidente norteamericano, ocupado ahora en la campa\u00f1a de elecciones al Congreso en el ecuador de su mandato, se ha forjado una imagen de l\u00e1tigo acusador de los excesos financieros de Wall Street. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[68,154,215,476,537,705],"class_list":["post-176","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-bancos","tag-contradiccion","tag-economia","tag-medios","tag-obama","tag-summers"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/comments?post=176"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/176\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/media?parent=176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/categories?post=176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/tags?post=176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}