{"id":13,"date":"2007-12-17T10:59:08","date_gmt":"2007-12-17T10:59:08","guid":{"rendered":"http:\/\/blogs.elcorreo.com\/aletheia\/?p=13"},"modified":"2007-12-17T10:59:08","modified_gmt":"2007-12-17T10:59:08","slug":"que-se-jodan","status":"publish","type":"post","link":"https:\/\/blogs.elcorreo.com\/aletheia\/2007\/12\/17\/que-se-jodan\/","title":{"rendered":"\u00a1Que se jodan!"},"content":{"rendered":"<p><IMG src=\"\/\/www.sibai.es\/img\/celebraciones%20familiares2.jpg\" id=\"img_0\"><\/p>\n<p>Leo en El Mundo que las dos principales empresas de alcohol del mundo (Pernod Ricard y Diageo) luchan por el liderazgo del sector en Espa\u00f1a en un momento econ\u00f3mico nada halag\u00fce\u00f1o. Las razones de este mal momento las conocemos todos: el alza cont\u00ednua del Euribor (y eso que dec\u00edan que en Espa\u00f1a la crisis de las hipotecas subprime estadounidenses no iba a tener gran incidencia. Pues s\u00ed la tiene, porque los bancos no tienen liquidez al no cobrar las hipotecas, desconf\u00edan entre s\u00ed para prestarse dinero \u2013que eso es el Eur\u00edbor- y la econom\u00eda se resiente) y la elevada inflaci\u00f3n que afecta especialmente al carro de la compra (4,1 %. Y podemos dar gracias, porque en Estonia se ha disparado a m\u00e1s del 10%).<\/p>\n<p>    El caso es que estas empresas tienen que afrontar adem\u00e1s el problema del descenso del consumo de alcohol en nuestro pa\u00eds. Los h\u00e1bitos de vida m\u00e1s saludables y la presi\u00f3n ejercida sobre los conductores explicar\u00edan este descenso; pero no todo est\u00e1 perdido. Se bebe menos, quiz\u00e1s s\u00ed; pero tambi\u00e9n se bebe m\u00e1s caro, se apuesta por bebidas m\u00e1s sofisticadas, con lo que las empresas se agarran a ello para dar continuidad a su negocio. Y ya se sabe que las Navidades no son malas fechas en lo que a celebraciones se refiere.<\/p>\n<p>    Tendr\u00edamos que reflexionar sobre la estrecha ligaz\u00f3n que tenemos en nuestra cultura entre fiesta y alcohol. A nuestros ojos, la primera sin el segundo parecer\u00eda no tener sentido; incluso los triunfos (deportivos y no deportivos) se celebran  descorchando botellas del espirituoso l\u00edquido. No es de extra\u00f1ar, pues la tradici\u00f3n religiosa en la que nos sustentamos (guste o no) hace del vino la sangre del Se\u00f1or y las vi\u00f1as pueblan los evangelios\u2026<\/p>\n<p>    La relaci\u00f3n del ser humano con el alcohol es muy larga. Desde que nos dimos cuenta de que la levadura pod\u00eda convertir el az\u00facar en etanol (en esto consiste la fermentaci\u00f3n), nos hemos dado a su aprovechamiento de todas las formas posibles: uvas, manzanas, ma\u00edz\u2026e \u00a1incluso leche y chocolate!, como hicieron los mongoles y las culturas centroamericanas respectivamente. No es de extra\u00f1ar. Al margen de los efectos desinhibidores que son bien conocidos, el alcohol es una excelente fuente de energ\u00eda (mejor que los hidratos o las prote\u00ednas y s\u00f3lo por debajo de las grasas) y evita enfermedades digestivas que s\u00ed pueden acontecer con agua contaminada. Sin embargo, ya es hora de dar un paso al frente y darnos cuenta del tremendo problema cultural que tenemos. Este maldito l\u00edquido destroza no s\u00f3lo la vida del que la ingiere en exceso, sino tambi\u00e9n la de su familia. La figura del \u201ctxikitero\u201d deber\u00eda ser tan denostada como lo est\u00e1 siendo la del fumador. La ministra Salgado ya intent\u00f3 implementar alguna medida, pero el sector se tir\u00f3 a su gaznate e hizo presa. Maldita la gracia. \u00a1Y que se jodan Pernod Ricard y Diageo!<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Leo en El Mundo que las dos principales empresas de alcohol del mundo (Pernod Ricard y Diageo) luchan por el liderazgo del sector en Espa\u00f1a en un momento econ\u00f3mico nada halag\u00fce\u00f1o. Las razones de este mal momento las conocemos todos: el alza cont\u00ednua del Euribor (y eso que dec\u00edan que en Espa\u00f1a la crisis de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31,153,276],"class_list":["post-13","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-alcohol","tag-consumo","tag-fiestas"],"_links":{"self":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/posts\/13\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/media?parent=13"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/categories?post=13"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcorreo.com\/aletheia\/wp-json\/wp\/v2\/tags?post=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}